{"id":7846,"date":"2025-02-24T15:15:41","date_gmt":"2025-02-24T16:15:41","guid":{"rendered":"https:\/\/karbord.io\/blog\/?p=7846"},"modified":"2025-02-25T06:49:37","modified_gmt":"2025-02-25T07:49:37","slug":"best-jobs-in-qazvin","status":"publish","type":"post","link":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/","title":{"rendered":"\u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u061b \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u060c \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0648 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u0645\u0648\u0642\u0639\u06cc\u062a \u062c\u063a\u0631\u0627\u0641\u06cc\u0627\u06cc\u06cc \u0645\u0646\u0627\u0633\u0628\u060c \u0646\u0632\u062f\u06cc\u06a9\u06cc \u0628\u0647 \u067e\u0627\u06cc\u062a\u062e\u062a\u060c \u0648\u062c\u0648\u062f \u0634\u0647\u0631\u06a9\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc \u0628\u0632\u0631\u06af \u0648 \u062a\u0648\u0644\u06cc\u062f\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0645\u062a\u0646\u0648\u0639\u060c \u0627\u0633\u062a\u0627\u0646 \u0642\u0632\u0648\u06cc\u0646 \u0631\u0627 \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0646\u0627\u0637\u0642 \u0628\u0627 \u067e\u062a\u0627\u0646\u0633\u06cc\u0644 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0628\u0627 \u0627\u06cc\u0646\u200c \u062d\u0627\u0644\u060c \u0645\u0627\u0646\u0646\u062f \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631\u060c \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0646\u06cc\u0632 \u0628\u0627 \u0686\u0627\u0644\u0634\u200c\u0647\u0627 \u0648 \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u062e\u0627\u0635 \u062e\u0648\u062f \u0631\u0648 \u0628\u0647\u200c \u0631\u0648 \u0627\u0633\u062a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647\u060c \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u0645\u062e\u062a\u0644\u0641\u060c \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0648 \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634 \u0631\u0648\u06cc \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u0648 \u06a9\u0627\u0631\u0622\u0641\u0631\u06cc\u0646\u0627\u0646 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0648\u0636\u0639\u06cc\u062a \u0627\u0634\u062a\u063a\u0627\u0644 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u0647\u0631\u0647\u200c \u0648\u0631\u06cc \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631 \u0627\u0631\u0627\u0626\u0647 \u062e\u0648\u0627\u0647\u06cc\u0645 \u062f\u0627\u062f \u062a\u0627 \u062f\u06cc\u062f\u06cc \u062c\u0627\u0645\u0639 \u0627\u0632 \u0634\u0631\u0627\u06cc\u0637 \u06a9\u0627\u0631\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/span><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_63 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\r\n<div class=\"ez-toc-title-container\">\r\n<p class=\"ez-toc-title \" >Table of Contents<\/p>\r\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\r\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%A2%D8%B4%D9%86%D8%A7%DB%8C%DB%8C_%D8%A8%D8%A7_%D9%88%D8%B6%D8%B9%DB%8C%D8%AA_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D9%82%D8%B2%D9%88%DB%8C%D9%86\" title=\"\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\">\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%A7%D9%87%D9%85%DB%8C%D8%AA_%D8%A8%D8%B1%D8%B1%D8%B3%DB%8C_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D9%88_%D8%B4%D9%86%D8%A7%D8%AE%D8%AA_%D9%81%D8%B1%D8%B5%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%B4%D8%BA%D9%84%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%DA%A9%D8%A7%D8%B1%D8%AC%D9%88%DB%8C%D8%A7%D9%86_%D9%88_%D8%B3%D8%B1%D9%85%D8%A7%DB%8C%D9%87%E2%80%8C%DA%AF%D8%B0%D8%A7%D8%B1%D8%A7%D9%86\" title=\"\u0627\u0647\u0645\u06cc\u062a \u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u0634\u0646\u0627\u062e\u062a \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u0648 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646\">\u0627\u0647\u0645\u06cc\u062a \u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u0634\u0646\u0627\u062e\u062a \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u0648 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%DA%A9%D9%85%DA%A9_%D8%A8%D9%87_%DA%A9%D8%A7%D8%B1%D8%AC%D9%88%DB%8C%D8%A7%D9%86_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D9%85%D8%B3%DB%8C%D8%B1_%D8%B4%D8%BA%D9%84%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8\" title=\"\u06a9\u0645\u06a9 \u0628\u0647 \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0633\u06cc\u0631 \u0634\u063a\u0644\u06cc \u0645\u0646\u0627\u0633\u0628\">\u06a9\u0645\u06a9 \u0628\u0647 \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0633\u06cc\u0631 \u0634\u063a\u0644\u06cc \u0645\u0646\u0627\u0633\u0628<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%DA%A9%D8%A7%D9%87%D8%B4_%D9%86%D8%B1%D8%AE_%D8%A8%DB%8C%DA%A9%D8%A7%D8%B1%DB%8C_%D9%88_%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%A7%D8%B4%D8%AA%D8%BA%D8%A7%D9%84%E2%80%8C\" title=\"\u06a9\u0627\u0647\u0634 \u0646\u0631\u062e \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0634\u062a\u063a\u0627\u0644\u200c\">\u06a9\u0627\u0647\u0634 \u0646\u0631\u062e \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0634\u062a\u063a\u0627\u0644\u200c<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%AC%D8%B0%D8%A8_%D8%B3%D8%B1%D9%85%D8%A7%DB%8C%D9%87%E2%80%8C%DA%AF%D8%B0%D8%A7%D8%B1%D8%A7%D9%86_%D9%88_%D8%AA%D9%88%D8%B3%D8%B9%D9%87_%D8%A7%D9%82%D8%AA%D8%B5%D8%A7%D8%AF%DB%8C\" title=\"\u062c\u0630\u0628 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0648 \u062a\u0648\u0633\u0639\u0647 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\">\u062c\u0630\u0628 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0648 \u062a\u0648\u0633\u0639\u0647 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%A8%D9%87%D8%B1%D9%87%E2%80%8C_%D9%88%D8%B1%DB%8C_%D9%86%DB%8C%D8%B1%D9%88%DB%8C_%DA%A9%D8%A7%D8%B1\" title=\"\u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u0647\u0631\u0647\u200c \u0648\u0631\u06cc \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631\">\u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u0647\u0631\u0647\u200c \u0648\u0631\u06cc \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D9%85%D9%87%D8%A7%D8%AC%D8%B1%D8%AA_%D9%86%DB%8C%D8%B1%D9%88%DB%8C_%DA%A9%D8%A7%D8%B1_%D9%85%D8%AA%D8%AE%D8%B5%D8%B5\" title=\"\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0645\u0647\u0627\u062c\u0631\u062a \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631 \u0645\u062a\u062e\u0635\u0635\">\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0645\u0647\u0627\u062c\u0631\u062a \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631 \u0645\u062a\u062e\u0635\u0635<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D9%85%D8%B4%D8%A7%D8%BA%D9%84_%D9%BE%D8%B1%D8%AF%D8%B1%D8%A2%D9%85%D8%AF_%D8%AF%D8%B1_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D9%82%D8%B2%D9%88%DB%8C%D9%86\" title=\"\u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\">\u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%B5%D9%86%D8%A7%DB%8C%D8%B9_%D8%AA%D9%88%D9%84%DB%8C%D8%AF%DB%8C_%D9%88_%D9%85%D8%AF%DB%8C%D8%B1%DB%8C%D8%AA_%DA%A9%D8%A7%D8%B1%D8%AE%D8%A7%D9%86%D9%87%E2%80%8C%D9%87%D8%A7\" title=\"\u0635\u0646\u0627\u06cc\u0639 \u062a\u0648\u0644\u06cc\u062f\u06cc \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627\">\u0635\u0646\u0627\u06cc\u0639 \u062a\u0648\u0644\u06cc\u062f\u06cc \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%AD%D9%88%D8%B2%D9%87_%D9%81%D9%86%D8%A7%D9%88%D8%B1%DB%8C_%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D9%88_%D8%A8%D8%B1%D9%86%D8%A7%D9%85%D9%87%E2%80%8C%D9%86%D9%88%DB%8C%D8%B3%DB%8C\" title=\"\u062d\u0648\u0632\u0647 \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0648 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0646\u0648\u06cc\u0633\u06cc\">\u062d\u0648\u0632\u0647 \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0648 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0646\u0648\u06cc\u0633\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D9%BE%D8%B2%D8%B4%DA%A9%DB%8C_%D9%88_%D8%AE%D8%AF%D9%85%D8%A7%D8%AA_%D8%AF%D8%B1%D9%85%D8%A7%D9%86%DB%8C\" title=\"\u067e\u0632\u0634\u06a9\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a \u062f\u0631\u0645\u0627\u0646\u06cc\">\u067e\u0632\u0634\u06a9\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a \u062f\u0631\u0645\u0627\u0646\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D9%85%D8%B4%D8%A7%D8%BA%D9%84_%D9%85%D8%B1%D8%AA%D8%A8%D8%B7_%D8%A8%D8%A7_%D8%A8%D8%A7%D8%B2%D8%B1%DA%AF%D8%A7%D9%86%DB%8C_%D9%88_%D8%B5%D8%A7%D8%AF%D8%B1%D8%A7%D8%AA\" title=\"\u0645\u0634\u0627\u063a\u0644 \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u0648 \u0635\u0627\u062f\u0631\u0627\u062a\">\u0645\u0634\u0627\u063a\u0644 \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u0648 \u0635\u0627\u062f\u0631\u0627\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%DA%A9%D8%B4%D8%A7%D9%88%D8%B1%D8%B2%DB%8C_%D9%88_%D8%B5%D9%86%D8%A7%DB%8C%D8%B9_%D9%88%D8%A7%D8%A8%D8%B3%D8%AA%D9%87\" title=\"\u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639 \u0648\u0627\u0628\u0633\u062a\u0647\">\u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639 \u0648\u0627\u0628\u0633\u062a\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%B5%D9%86%D8%B9%D8%AA_%DA%AF%D8%B1%D8%AF%D8%B4%DA%AF%D8%B1%DB%8C_%D9%88_%D9%87%D8%AA%D9%84%D8%AF%D8%A7%D8%B1%DB%8C\" title=\"\u0635\u0646\u0639\u062a \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0648 \u0647\u062a\u0644\u062f\u0627\u0631\u06cc\">\u0635\u0646\u0639\u062a \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0648 \u0647\u062a\u0644\u062f\u0627\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D9%85%D8%B4%D8%A7%D8%BA%D9%84_%D9%81%D9%86%DB%8C_%D9%88_%D9%85%D9%87%D9%86%D8%AF%D8%B3%DB%8C\" title=\"\u0645\u0634\u0627\u063a\u0644 \u0641\u0646\u06cc \u0648 \u0645\u0647\u0646\u062f\u0633\u06cc\">\u0645\u0634\u0627\u063a\u0644 \u0641\u0646\u06cc \u0648 \u0645\u0647\u0646\u062f\u0633\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D9%81%D8%B1%D9%88%D8%B4_%D9%88_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1%DB%8C%D8%A7%D8%A8%DB%8C\" title=\"\u0641\u0631\u0648\u0634 \u0648 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc\">\u0641\u0631\u0648\u0634 \u0648 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%DA%86%D8%A7%D9%84%D8%B4%E2%80%8C%D9%87%D8%A7_%D9%88_%D9%85%D9%88%D8%A7%D9%86%D8%B9_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D9%82%D8%B2%D9%88%DB%8C%D9%86\" title=\"\u0686\u0627\u0644\u0634\u200c\u0647\u0627 \u0648 \u0645\u0648\u0627\u0646\u0639 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\">\u0686\u0627\u0644\u0634\u200c\u0647\u0627 \u0648 \u0645\u0648\u0627\u0646\u0639 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D9%85%D8%B4%DA%A9%D9%84%D8%A7%D8%AA_%D8%A8%DB%8C%DA%A9%D8%A7%D8%B1%DB%8C_%D9%88_%DA%A9%D9%85%D8%A8%D9%88%D8%AF_%D9%81%D8%B1%D8%B5%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%B4%D8%BA%D9%84%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%81%D8%A7%D8%B1%D8%BA%E2%80%8C%D8%A7%D9%84%D8%AA%D8%AD%D8%B5%DB%8C%D9%84%D8%A7%D9%86\" title=\"\u0645\u0634\u06a9\u0644\u0627\u062a \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0648 \u06a9\u0645\u0628\u0648\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0628\u0631\u0627\u06cc \u0641\u0627\u0631\u063a\u200c\u0627\u0644\u062a\u062d\u0635\u06cc\u0644\u0627\u0646\">\u0645\u0634\u06a9\u0644\u0627\u062a \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0648 \u06a9\u0645\u0628\u0648\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0628\u0631\u0627\u06cc \u0641\u0627\u0631\u063a\u200c\u0627\u0644\u062a\u062d\u0635\u06cc\u0644\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%AA%D8%A3%D8%AB%DB%8C%D8%B1_%D8%B4%D8%B1%D8%A7%DB%8C%D8%B7_%D8%A7%D9%82%D8%AA%D8%B5%D8%A7%D8%AF%DB%8C_%DA%A9%D8%B4%D9%88%D8%B1_%D8%A8%D8%B1_%DA%A9%D8%B3%D8%A8%E2%80%8C_%D9%88_%DA%A9%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D9%85%D8%AD%D9%84%DB%8C\" title=\"\u062a\u0623\u062b\u06cc\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u06a9\u0634\u0648\u0631 \u0628\u0631 \u06a9\u0633\u0628\u200c \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u062d\u0644\u06cc\">\u062a\u0623\u062b\u06cc\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u06a9\u0634\u0648\u0631 \u0628\u0631 \u06a9\u0633\u0628\u200c \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u062d\u0644\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%DA%A9%D9%85%D8%A8%D9%88%D8%AF_%D8%B3%D8%B1%D9%85%D8%A7%DB%8C%D9%87%E2%80%8C_%DA%AF%D8%B0%D8%A7%D8%B1%DB%8C_%D8%AF%D8%B1_%D8%A8%D8%B1%D8%AE%DB%8C_%D8%A8%D8%AE%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D9%82%D8%AA%D8%B5%D8%A7%D8%AF%DB%8C\" title=\"\u06a9\u0645\u0628\u0648\u062f \u0633\u0631\u0645\u0627\u06cc\u0647\u200c \u06af\u0630\u0627\u0631\u06cc \u062f\u0631 \u0628\u0631\u062e\u06cc \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\">\u06a9\u0645\u0628\u0648\u062f \u0633\u0631\u0645\u0627\u06cc\u0647\u200c \u06af\u0630\u0627\u0631\u06cc \u062f\u0631 \u0628\u0631\u062e\u06cc \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%B1%D8%A7%D9%87%DA%A9%D8%A7%D8%B1%D9%87%D8%A7_%D9%88_%D9%BE%DB%8C%D8%B4%D9%86%D9%87%D8%A7%D8%AF%D9%87%D8%A7_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A8%D9%87%D8%A8%D9%88%D8%AF_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D9%82%D8%B2%D9%88%DB%8C%D9%86\" title=\"\u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627 \u0648 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u0647\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\">\u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627 \u0648 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u0647\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%AA%D9%88%D8%B3%D8%B9%D9%87_%D8%A7%D8%B3%D8%AA%D8%A7%D8%B1%D8%AA%D8%A7%D9%BE%E2%80%8C%D9%87%D8%A7_%D9%88_%D8%AD%D9%85%D8%A7%DB%8C%D8%AA_%D8%A7%D8%B2_%DA%A9%D8%A7%D8%B1%D8%A2%D9%81%D8%B1%DB%8C%D9%86%DB%8C\" title=\"\u062a\u0648\u0633\u0639\u0647 \u0627\u0633\u062a\u0627\u0631\u062a\u0627\u067e\u200c\u0647\u0627 \u0648 \u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u06a9\u0627\u0631\u0622\u0641\u0631\u06cc\u0646\u06cc\">\u062a\u0648\u0633\u0639\u0647 \u0627\u0633\u062a\u0627\u0631\u062a\u0627\u067e\u200c\u0647\u0627 \u0648 \u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u06a9\u0627\u0631\u0622\u0641\u0631\u06cc\u0646\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D9%85%D9%87%D8%A7%D8%B1%D8%AA%E2%80%8C_%D8%A2%D9%85%D9%88%D8%B2%DB%8C_%D9%88_%D8%A2%D9%85%D9%88%D8%B2%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%81%D9%86%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%D9%88%D8%A7%D9%86%D8%A7%D9%86\" title=\"\u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u0647\u0627\u0631\u062a\u200c \u0622\u0645\u0648\u0632\u06cc \u0648 \u0622\u0645\u0648\u0632\u0634\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u0628\u0631\u0627\u06cc \u062c\u0648\u0627\u0646\u0627\u0646\">\u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u0647\u0627\u0631\u062a\u200c \u0622\u0645\u0648\u0632\u06cc \u0648 \u0622\u0645\u0648\u0632\u0634\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u0628\u0631\u0627\u06cc \u062c\u0648\u0627\u0646\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%B3%D8%B1%D9%85%D8%A7%DB%8C%D9%87%E2%80%8C%DA%AF%D8%B0%D8%A7%D8%B1%DB%8C_%D8%A8%DB%8C%D8%B4%D8%AA%D8%B1_%D8%AF%D8%B1_%D8%A8%D8%AE%D8%B4_%DA%AF%D8%B1%D8%AF%D8%B4%DA%AF%D8%B1%DB%8C_%D9%88_%D9%81%D9%86%D8%A7%D9%88%D8%B1%DB%8C_%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA\" title=\"\u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631 \u0628\u062e\u0634 \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0648 \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a\">\u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631 \u0628\u062e\u0634 \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0648 \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%A7%D9%81%D8%B1%D8%A7%D8%AF_%D8%AF%D8%B1_%D9%82%D8%B2%D9%88%DB%8C%D9%86_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D9%85%DB%8C%E2%80%8C%D8%AA%D9%88%D8%A7%D9%86%D9%86%D8%AF_%D9%81%D8%B1%D8%B5%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%B4%D8%BA%D9%84%DB%8C_%D8%B1%D8%A7_%D9%BE%DB%8C%D8%AF%D8%A7_%DA%A9%D9%86%D9%86%D8%AF%D8%9F\" title=\"\u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0631\u0627 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f\u061f\">\u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0631\u0627 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C\" title=\"\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc\">\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc<\/a><\/li><\/ul><\/nav><\/div>\r\n<h2><span class=\"ez-toc-section\" id=\"%D8%A2%D8%B4%D9%86%D8%A7%DB%8C%DB%8C_%D8%A8%D8%A7_%D9%88%D8%B6%D8%B9%DB%8C%D8%AA_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D9%82%D8%B2%D9%88%DB%8C%D9%86\"><\/span>\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0627\u0633\u062a\u0627\u0646 \u0642\u0632\u0648\u06cc\u0646 \u0628\u0627 \u062f\u0627\u0634\u062a\u0646 \u0634\u0647\u0631\u06a9\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc \u0645\u062a\u0639\u062f\u062f\u060c \u0628\u062e\u0634 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0648 \u0638\u0631\u0641\u06cc\u062a\u200c\u0647\u0627\u06cc \u06af\u0631\u062f\u0634\u06af\u0631\u06cc\u060c \u0633\u0647\u0645 \u062e\u0648\u0628\u06cc \u062f\u0631 \u062a\u0648\u0644\u06cc\u062f \u0648 \u0627\u0634\u062a\u063a\u0627\u0644 \u06a9\u0634\u0648\u0631 \u062f\u0627\u0631\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0628\u062e\u0634 \u0635\u0646\u0639\u062a\u06cc \u0642\u0632\u0648\u06cc\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u067e\u0627\u06cc\u0647\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0627\u0633\u062a. \u0648\u062c\u0648\u062f \u0634\u0647\u0631\u06a9\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc \u0628\u0632\u0631\u06af \u0645\u0627\u0646\u0646\u062f \u0634\u0647\u0631\u06a9 \u0635\u0646\u0639\u062a\u06cc \u0627\u0644\u0628\u0631\u0632\u060c \u06a9\u0627\u0633\u067e\u06cc\u0646\u060c \u0644\u06cc\u0627 \u0648 \u0622\u0628\u06cc\u06a9 \u0628\u0627\u0639\u062b \u0634\u062f\u0647 \u062a\u0627 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06cc \u0648 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0646\u0637\u0642\u0647 \u0641\u0639\u0627\u0644\u06cc\u062a \u06a9\u0646\u0646\u062f. \u0635\u0646\u0627\u06cc\u0639 \u0641\u0639\u0627\u0644 \u062f\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0634\u0627\u0645\u0644 \u0635\u0646\u0627\u06cc\u0639 \u062e\u0648\u062f\u0631\u0648\u0633\u0627\u0632\u06cc\u060c \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc\u060c \u063a\u0630\u0627\u06cc\u06cc\u060c \u062f\u0627\u0631\u0648\u06cc\u06cc\u060c \u0641\u0644\u0632\u06cc \u0648 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0645\u062a\u0639\u062f\u062f\u06cc \u0628\u0631\u0627\u06cc \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631 \u0645\u0627\u0647\u0631 \u0648 \u063a\u06cc\u0631\u0645\u0627\u0647\u0631 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0635\u0646\u0639\u062a\u060c \u0628\u062e\u0634 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0646\u06cc\u0632 \u062f\u0631 \u0627\u0642\u062a\u0635\u0627\u062f \u0642\u0632\u0648\u06cc\u0646 \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u062f\u0627\u0631\u062f. \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062f\u0627\u0634\u062a\u0646 \u0632\u0645\u06cc\u0646\u200c\u0647\u0627\u06cc \u062d\u0627\u0635\u0644\u062e\u06cc\u0632 \u0648 \u0634\u0631\u0627\u06cc\u0637 \u0627\u0642\u0644\u06cc\u0645\u06cc \u0645\u0646\u0627\u0633\u0628\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0631\u0627\u06a9\u0632 \u0645\u0647\u0645 \u062a\u0648\u0644\u06cc\u062f \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u0645\u0627\u0646\u0646\u062f \u0627\u0646\u06af\u0648\u0631\u060c \u0632\u06cc\u062a\u0648\u0646\u060c \u067e\u0633\u062a\u0647 \u0648 \u06af\u0646\u062f\u0645 \u062f\u0631 \u06a9\u0634\u0648\u0631 \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u062f\u0627\u0645\u062f\u0627\u0631\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639 \u0648\u0627\u0628\u0633\u062a\u0647 \u0628\u0647 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u0641\u0631\u0622\u0648\u0631\u06cc \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0648 \u0644\u0628\u0646\u06cc\u0627\u062a \u0646\u06cc\u0632 \u062f\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0631\u0648\u0646\u0642 \u062f\u0627\u0631\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0627\u0632 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631\u060c \u0628\u062e\u0634 \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a \u0646\u06cc\u0632 \u062f\u0631 \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u0627\u062e\u06cc\u0631 \u0631\u0634\u062f \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a. \u0648\u062c\u0648\u062f \u0628\u0646\u0627\u0647\u0627\u06cc \u062a\u0627\u0631\u06cc\u062e\u06cc \u0645\u0627\u0646\u0646\u062f \u0645\u06cc\u062f\u0627\u0646 \u0622\u0632\u0627\u062f\u06cc (\u0633\u0628\u0632\u0647\u200c\u0645\u06cc\u062f\u0627\u0646)\u060c \u0633\u0631\u0627\u06cc \u0633\u0639\u062f\u0627\u0644\u0633\u0644\u0637\u0646\u0647\u060c \u0642\u0644\u0639\u0647 \u0627\u0644\u0645\u0648\u062a \u0648 \u06a9\u0627\u0631\u0648\u0627\u0646\u0633\u0631\u0627\u0647\u0627\u06cc \u0642\u062f\u06cc\u0645\u06cc \u0628\u0627\u0639\u062b \u0634\u062f\u0647 \u062a\u0627 \u0642\u0632\u0648\u06cc\u0646 \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0642\u0627\u0635\u062f \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0641\u0631\u0647\u0646\u06af\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0634\u0648\u062f. \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0628\u0647 \u0627\u06cc\u062c\u0627\u062f \u0627\u0634\u062a\u063a\u0627\u0644 \u062f\u0631 \u062d\u0648\u0632\u0647\u200c\u0647\u0627\u06cc \u0645\u0631\u062a\u0628\u0637 \u0645\u0627\u0646\u0646\u062f \u0647\u062a\u0644\u062f\u0627\u0631\u06cc\u060c \u0631\u0633\u062a\u0648\u0631\u0627\u0646\u200c \u062f\u0627\u0631\u06cc\u060c \u0631\u0627\u0647\u0646\u0645\u0627\u06cc\u06cc \u062a\u0648\u0631 \u0648 \u0635\u0646\u0627\u06cc\u0639\u200c \u062f\u0633\u062a\u06cc \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<p><a href=\"https:\/\/karbord.io\/jobs\/in-ghazvin-cities\" target=\"_blank\" rel=\"noopener\">\u06a9\u0627\u0631\u06cc\u0627\u0628\u06cc \u0642\u0632\u0648\u06cc\u0646<\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D9%87%D9%85%DB%8C%D8%AA_%D8%A8%D8%B1%D8%B1%D8%B3%DB%8C_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D9%88_%D8%B4%D9%86%D8%A7%D8%AE%D8%AA_%D9%81%D8%B1%D8%B5%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%B4%D8%BA%D9%84%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%DA%A9%D8%A7%D8%B1%D8%AC%D9%88%DB%8C%D8%A7%D9%86_%D9%88_%D8%B3%D8%B1%D9%85%D8%A7%DB%8C%D9%87%E2%80%8C%DA%AF%D8%B0%D8%A7%D8%B1%D8%A7%D9%86\"><\/span>\u0627\u0647\u0645\u06cc\u062a \u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u0634\u0646\u0627\u062e\u062a \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u0648 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u0634\u0646\u0627\u062e\u062a \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u06af\u0627\u0645\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u062a\u0635\u0645\u06cc\u0645\u200c\u06af\u06cc\u0631\u06cc \u0622\u06af\u0627\u0647\u0627\u0646\u0647 \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0627\u0634\u062a\u063a\u0627\u0644 \u0648 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c \u06af\u0630\u0627\u0631\u06cc \u0627\u0633\u062a. \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0627\u0645\u0631\u0648\u0632 \u06a9\u0647 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u0641\u0646\u0627\u0648\u0631\u06cc \u0628\u0647 \u0633\u0631\u0639\u062a \u062f\u0631 \u062d\u0627\u0644 \u0631\u062e \u062f\u0627\u062f\u0646 \u0647\u0633\u062a\u0646\u062f\u060c \u0622\u06af\u0627\u0647\u06cc \u0627\u0632 \u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0645\u0633\u06cc\u0631 \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0627\u0641\u0631\u0627\u062f \u0648 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u06a9\u0633\u0628\u200c \u0648 \u06a9\u0627\u0631\u0647\u0627 \u0631\u0627 \u062a\u062d\u062a \u062a\u0623\u062b\u06cc\u0631 \u0642\u0631\u0627\u0631 \u062f\u0647\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%DA%A9%D9%85%DA%A9_%D8%A8%D9%87_%DA%A9%D8%A7%D8%B1%D8%AC%D9%88%DB%8C%D8%A7%D9%86_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D9%85%D8%B3%DB%8C%D8%B1_%D8%B4%D8%BA%D9%84%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8\"><\/span>\u06a9\u0645\u06a9 \u0628\u0647 \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0633\u06cc\u0631 \u0634\u063a\u0644\u06cc \u0645\u0646\u0627\u0633\u0628<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0634\u0646\u0627\u062e\u062a \u062f\u0642\u06cc\u0642 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0628\u0647 \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0628\u0631 \u0627\u0633\u0627\u0633 \u062a\u0642\u0627\u0636\u0627\u06cc \u0634\u063a\u0644\u06cc \u0648 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0645\u0648\u0631\u062f\u0646\u06cc\u0627\u0632\u060c \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u0646\u062f. \u0622\u06af\u0627\u0647\u06cc \u0627\u0632 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f\u060c \u0635\u0646\u0627\u06cc\u0639 \u062f\u0631 \u062d\u0627\u0644 \u0631\u0634\u062f \u0648 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u067e\u0631\u062a\u0642\u0627\u0636\u0627 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u062a\u0635\u0645\u06cc\u0645\u200c\u06af\u06cc\u0631\u06cc \u0628\u0647\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u0622\u06cc\u0646\u062f\u0647 \u0634\u063a\u0644\u06cc \u062e\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u0648 \u0627\u0632 \u0627\u062a\u0644\u0627\u0641 \u0632\u0645\u0627\u0646 \u0648 \u0647\u0632\u06cc\u0646\u0647 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u0646\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D9%87%D8%B4_%D9%86%D8%B1%D8%AE_%D8%A8%DB%8C%DA%A9%D8%A7%D8%B1%DB%8C_%D9%88_%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%A7%D8%B4%D8%AA%D8%BA%D8%A7%D9%84%E2%80%8C\"><\/span>\u06a9\u0627\u0647\u0634 \u0646\u0631\u062e \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0634\u062a\u063a\u0627\u0644\u200c<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u0648 \u0641\u0627\u0631\u063a\u200c\u0627\u0644\u062a\u062d\u0635\u06cc\u0644\u0627\u0646 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0628\u0627\u0632\u0627\u0631\u0647\u0627 \u0631\u0627 \u06a9\u0633\u0628 \u06a9\u0631\u062f\u0647 \u0648 \u0634\u0627\u0646\u0633 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u062e\u0648\u062f \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u0646\u062f. \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0646\u062f\u0627\u0634\u062a\u0646 \u0622\u06af\u0627\u0647\u06cc \u06a9\u0627\u0641\u06cc \u0627\u0632 \u0648\u0636\u0639\u06cc\u062a \u0634\u063a\u0644\u06cc\u060c \u062f\u0631 \u0645\u0634\u0627\u063a\u0644\u06cc \u0641\u0639\u0627\u0644\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u06a9\u0647 \u062f\u0631\u0622\u0645\u062f \u0645\u0646\u0627\u0633\u0628\u06cc \u0646\u062f\u0627\u0631\u0646\u062f\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627 \u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0628\u0647\u062a\u0631\u060c \u0622\u06cc\u0646\u062f\u0647 \u0628\u0647\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u062f \u0631\u0642\u0645 \u0628\u0632\u0646\u0646\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AC%D8%B0%D8%A8_%D8%B3%D8%B1%D9%85%D8%A7%DB%8C%D9%87%E2%80%8C%DA%AF%D8%B0%D8%A7%D8%B1%D8%A7%D9%86_%D9%88_%D8%AA%D9%88%D8%B3%D8%B9%D9%87_%D8%A7%D9%82%D8%AA%D8%B5%D8%A7%D8%AF%DB%8C\"><\/span>\u062c\u0630\u0628 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0648 \u062a\u0648\u0633\u0639\u0647 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0628\u0627 \u0645\u0637\u0627\u0644\u0639\u0647 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u0634\u0646\u0627\u062e\u062a \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0648 \u0638\u0631\u0641\u06cc\u062a\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u0633\u062a\u0627\u0646 \u0642\u0632\u0648\u06cc\u0646\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u06a9\u0633\u0628\u200c \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f\u06cc \u0631\u0627\u0647\u200c \u0627\u0646\u062f\u0627\u0632\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0647\u0645 \u0628\u0647 \u062a\u0648\u0633\u0639\u0647 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0645\u0646\u0637\u0642\u0647 \u06a9\u0645\u06a9 \u06a9\u0646\u062f \u0648 \u0647\u0645 \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u062f. \u0634\u0646\u0627\u062e\u062a \u062d\u0648\u0632\u0647\u200c\u0647\u0627\u06cc \u067e\u0631\u0631\u0648\u0646\u0642 \u0645\u0627\u0646\u0646\u062f \u0635\u0646\u0639\u062a\u060c \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a\u060c \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0648 \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0628\u0647 \u0622\u0646\u200c\u0647\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u0628\u0647\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0628\u06af\u06cc\u0631\u0646\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%A8%D9%87%D8%B1%D9%87%E2%80%8C_%D9%88%D8%B1%DB%8C_%D9%86%DB%8C%D8%B1%D9%88%DB%8C_%DA%A9%D8%A7%D8%B1\"><\/span>\u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u0647\u0631\u0647\u200c \u0648\u0631\u06cc \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0627\u06af\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u062a\u062d\u0644\u06cc\u0644 \u0634\u0648\u062f\u060c \u0647\u0645 \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u0648 \u0647\u0645 \u06a9\u0627\u0631\u0641\u0631\u0645\u0627\u06cc\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647\u0631\u0647\u200c\u0648\u0631\u06cc \u062e\u0648\u062f \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u0646\u062f. \u06a9\u0627\u0631\u0641\u0631\u0645\u0627\u06cc\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0646\u06cc\u0631\u0648\u0647\u0627\u06cc \u0645\u062a\u062e\u0635\u0635 \u0648 \u0645\u0627\u0647\u0631 \u062c\u0630\u0628 \u06a9\u0646\u0646\u062f \u0648 \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631 \u0645\u0634\u0627\u063a\u0644\u06cc \u0641\u0639\u0627\u0644\u06cc\u062a \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u062a\u0637\u0627\u0628\u0642 \u0631\u0627 \u0628\u0627 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc\u200c\u0647\u0627 \u0648 \u0639\u0644\u0627\u0642\u0647\u200c\u0647\u0627\u06cc\u0634\u0627\u0646 \u062f\u0627\u0631\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D9%85%D9%87%D8%A7%D8%AC%D8%B1%D8%AA_%D9%86%DB%8C%D8%B1%D9%88%DB%8C_%DA%A9%D8%A7%D8%B1_%D9%85%D8%AA%D8%AE%D8%B5%D8%B5\"><\/span>\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0645\u0647\u0627\u062c\u0631\u062a \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631 \u0645\u062a\u062e\u0635\u0635<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u0627\u0632 \u062f\u0644\u0627\u06cc\u0644 \u0645\u0647\u0627\u062c\u0631\u062a \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631\u060c \u0646\u0628\u0648\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0645\u0646\u0627\u0633\u0628 \u0648 \u0639\u062f\u0645 \u0622\u06af\u0627\u0647\u06cc \u0627\u0632 \u0638\u0631\u0641\u06cc\u062a\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0627\u0633\u062a. \u0628\u0627 \u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0645\u0634\u0627\u063a\u0644 \u0628\u0627 \u062f\u0631\u0622\u0645\u062f \u0645\u0646\u0627\u0633\u0628 \u0648 \u0622\u06cc\u0646\u062f\u0647 \u0634\u063a\u0644\u06cc \u067e\u0627\u06cc\u062f\u0627\u0631 \u0631\u0627 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u06a9\u0631\u062f \u0648 \u0627\u0632 \u062e\u0631\u0648\u062c \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631 \u0645\u0627\u0647\u0631 \u0627\u0632 \u0627\u0633\u062a\u0627\u0646 \u06cc\u0627 \u06a9\u0634\u0648\u0631 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0631\u062f.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%85%D8%B4%D8%A7%D8%BA%D9%84_%D9%BE%D8%B1%D8%AF%D8%B1%D8%A2%D9%85%D8%AF_%D8%AF%D8%B1_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D9%82%D8%B2%D9%88%DB%8C%D9%86\"><\/span>\u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u0634\u0627\u063a\u0644\u06cc \u0631\u0627 \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u062f\u0631\u0622\u0645\u062f \u062e\u0648\u0628\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u0645\u0639\u0631\u0641\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645:<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B5%D9%86%D8%A7%DB%8C%D8%B9_%D8%AA%D9%88%D9%84%DB%8C%D8%AF%DB%8C_%D9%88_%D9%85%D8%AF%DB%8C%D8%B1%DB%8C%D8%AA_%DA%A9%D8%A7%D8%B1%D8%AE%D8%A7%D9%86%D9%87%E2%80%8C%D9%87%D8%A7\"><\/span>\u0635\u0646\u0627\u06cc\u0639 \u062a\u0648\u0644\u06cc\u062f\u06cc \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0642\u0632\u0648\u06cc\u0646 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062f\u0627\u0634\u062a\u0646 \u0634\u0647\u0631\u06a9\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc \u0645\u062a\u0639\u062f\u062f\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0642\u0637\u0628\u200c\u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0645\u062f\u06cc\u0631\u0627\u0646 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627\u060c \u0645\u0647\u0646\u062f\u0633\u0627\u0646 \u0635\u0646\u0627\u06cc\u0639 \u0648 \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a\u06cc \u0648 \u0646\u0638\u0627\u0631\u062a\u06cc \u0627\u06cc\u0646 \u0635\u0646\u0627\u06cc\u0639 \u0641\u0639\u0627\u0644\u06cc\u062a \u062f\u0627\u0631\u0646\u062f\u060c \u062f\u0631\u0622\u0645\u062f \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u062a\u0623\u0633\u06cc\u0633 \u06a9\u0627\u0631\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06cc \u062f\u0631 \u062d\u0648\u0632\u0647\u200c\u0647\u0627\u06cc \u063a\u0630\u0627\u06cc\u06cc\u060c \u062f\u0627\u0631\u0648\u06cc\u06cc\u060c \u062e\u0648\u062f\u0631\u0648\u0633\u0627\u0632\u06cc \u0648 \u0646\u0633\u0627\u062c\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0633\u0648\u062f\u0622\u0648\u0631 \u0628\u0627\u0634\u062f\u060c \u0632\u06cc\u0631\u0627 \u0627\u0633\u062a\u0627\u0646 \u0642\u0632\u0648\u06cc\u0646 \u0628\u0647 \u062a\u0647\u0631\u0627\u0646 \u0648 \u0633\u0627\u06cc\u0631 \u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u0647\u0645 \u06a9\u0634\u0648\u0631 \u0646\u0632\u062f\u06cc\u06a9 \u0627\u0633\u062a \u0648 \u0628\u0627\u0632\u0627\u0631 \u0645\u0635\u0631\u0641 \u06af\u0633\u062a\u0631\u062f\u0647\u200c\u0627\u06cc \u062f\u0627\u0631\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AD%D9%88%D8%B2%D9%87_%D9%81%D9%86%D8%A7%D9%88%D8%B1%DB%8C_%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D9%88_%D8%A8%D8%B1%D9%86%D8%A7%D9%85%D9%87%E2%80%8C%D9%86%D9%88%DB%8C%D8%B3%DB%8C\"><\/span>\u062d\u0648\u0632\u0647 \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0648 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0646\u0648\u06cc\u0633\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0628\u0627 \u06af\u0633\u062a\u0631\u0634 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062e\u062f\u0645\u0627\u062a \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644\u060c \u0645\u0634\u0627\u063a\u0644\u06cc \u0645\u0627\u0646\u0646\u062f \u0628\u0631\u0646\u0627\u0645\u0647\u200c \u0646\u0648\u06cc\u0633\u06cc\u060c \u0637\u0631\u0627\u062d\u06cc \u0633\u0627\u06cc\u062a\u060c \u062a\u0648\u0633\u0639\u0647 \u0627\u067e\u0644\u06cc\u06a9\u06cc\u0634\u0646 \u0648 \u0627\u0645\u0646\u06cc\u062a \u0633\u0627\u06cc\u0628\u0631\u06cc \u062c\u0632\u0648 \u067e\u0631\u062f\u0631\u0622\u0645\u062f\u062a\u0631\u06cc\u0646 \u0645\u0634\u0627\u063a\u0644 \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f. \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0646\u0648\u06cc\u0633\u0627\u0646 \u0648 \u0645\u062a\u062e\u0635\u0635\u0627\u0646 IT \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0635\u0648\u0631\u062a \u062f\u0648\u0631\u06a9\u0627\u0631\u06cc \u06cc\u0627 \u0641\u0631\u06cc\u0644\u0646\u0633\u0631\u06cc \u0628\u0631\u0627\u06cc \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0648 \u062e\u0627\u0631\u062c\u06cc \u0641\u0639\u0627\u0644\u06cc\u062a \u06a9\u0646\u0646\u062f \u0648 \u062f\u0631\u0622\u0645\u062f \u0645\u0646\u0627\u0633\u0628 \u06a9\u0633\u0628 \u06a9\u0646\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u0627\u0633\u062a\u0627\u0631\u062a\u0627\u067e\u200c\u0647\u0627\u06cc \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u06a9\u0645\u062a\u0631 \u0646\u0633\u0628\u062a \u0628\u0647 \u062a\u0647\u0631\u0627\u0646\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0622\u0641\u0631\u06cc\u0646\u0627\u0646 \u0628\u0627\u0634\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%BE%D8%B2%D8%B4%DA%A9%DB%8C_%D9%88_%D8%AE%D8%AF%D9%85%D8%A7%D8%AA_%D8%AF%D8%B1%D9%85%D8%A7%D9%86%DB%8C\"><\/span>\u067e\u0632\u0634\u06a9\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a \u062f\u0631\u0645\u0627\u0646\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u067e\u0632\u0634\u06a9\u0627\u0646 \u0639\u0645\u0648\u0645\u06cc\u060c \u062f\u0646\u062f\u0627\u0646\u200c\u067e\u0632\u0634\u06a9\u0627\u0646\u060c \u0645\u062a\u062e\u0635\u0635\u0627\u0646 \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0648 \u062c\u0631\u0627\u062d\u0627\u0646 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631\u0622\u0645\u062f \u062e\u0648\u0628\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062a\u0642\u0627\u0636\u0627 \u0628\u0631\u0627\u06cc \u062e\u062f\u0645\u0627\u062a \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0648 \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u062a\u0632\u0631\u06cc\u0642 \u0698\u0644 \u0648 \u0628\u0648\u062a\u0627\u06a9\u0633\u060c \u0644\u06cc\u0632\u0631 \u062f\u0631\u0645\u0627\u0646\u06cc \u0648 \u06a9\u0627\u0634\u062a \u0645\u0648\u060c \u06a9\u0644\u06cc\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc \u0632\u06cc\u0628\u0627\u06cc\u06cc \u062f\u0631\u0622\u0645\u062f \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u062a\u0623\u0633\u06cc\u0633 \u062f\u0627\u0631\u0648\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0648 \u0645\u0631\u0627\u06a9\u0632 \u062a\u0635\u0648\u06cc\u0631\u0628\u0631\u062f\u0627\u0631\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u06a9\u0645\u0628\u0648\u062f \u0627\u06cc\u0646 \u062e\u062f\u0645\u0627\u062a \u062f\u0631 \u0628\u0631\u062e\u06cc \u0645\u0646\u0627\u0637\u0642\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0633\u0648\u062f\u0622\u0648\u0631 \u0628\u0627\u0634\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D8%B4%D8%A7%D8%BA%D9%84_%D9%85%D8%B1%D8%AA%D8%A8%D8%B7_%D8%A8%D8%A7_%D8%A8%D8%A7%D8%B2%D8%B1%DA%AF%D8%A7%D9%86%DB%8C_%D9%88_%D8%B5%D8%A7%D8%AF%D8%B1%D8%A7%D8%AA\"><\/span>\u0645\u0634\u0627\u063a\u0644 \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u0648 \u0635\u0627\u062f\u0631\u0627\u062a<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0642\u0632\u0648\u06cc\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u0647\u0645 \u062f\u0631 \u062d\u0648\u0632\u0647 \u062a\u062c\u0627\u0631\u062a \u0648 \u0635\u0627\u062f\u0631\u0627\u062a \u0627\u0633\u062a. \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u062a\u0648\u0644\u06cc\u062f\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u0648 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0628\u0647 \u0633\u0627\u06cc\u0631 \u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627 \u0648 \u062d\u062a\u06cc \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u0635\u0627\u062f\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0645\u0634\u0627\u063a\u0644\u06cc \u0645\u0627\u0646\u0646\u062f \u0645\u062f\u06cc\u0631\u06cc\u062a \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc\u060c \u0635\u0627\u062f\u0631\u0627\u062a \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0648 \u0635\u0646\u0639\u062a\u06cc\u060c \u06a9\u0627\u0631\u06af\u0632\u0627\u0631\u06cc \u06af\u0645\u0631\u06a9 \u0648 \u062d\u0645\u0644\u200c \u0648 \u0646\u0642\u0644 \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u062f\u0631\u0622\u0645\u062f \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0628\u0627 \u0631\u0634\u062f \u062a\u062c\u0627\u0631\u062a \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u060c \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0622\u0646\u0644\u0627\u06cc\u0646 \u0648 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u062d\u0645\u0644\u200c\u0648\u0646\u0642\u0644 \u0648 \u0644\u062c\u0633\u062a\u06cc\u06a9\u060c \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0633\u0648\u062f\u0622\u0648\u0631\u06cc \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%DA%A9%D8%B4%D8%A7%D9%88%D8%B1%D8%B2%DB%8C_%D9%88_%D8%B5%D9%86%D8%A7%DB%8C%D8%B9_%D9%88%D8%A7%D8%A8%D8%B3%D8%AA%D9%87\"><\/span>\u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639 \u0648\u0627\u0628\u0633\u062a\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u062f\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u0645\u0627\u0646\u0646\u062f \u0627\u0646\u06af\u0648\u0631\u060c \u0632\u06cc\u062a\u0648\u0646\u060c \u067e\u0633\u062a\u0647 \u0648 \u06af\u0646\u062f\u0645 \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u0634\u0648\u062f. \u0645\u0634\u0627\u063a\u0644\u06cc \u0645\u0627\u0646\u0646\u062f \u06a9\u0634\u062a \u0648 \u0641\u0631\u0648\u0634 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc\u060c \u0628\u0633\u062a\u0647\u200c \u0628\u0646\u062f\u06cc \u0648 \u0641\u0631\u0622\u0648\u0631\u06cc \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc\u060c \u067e\u0631\u0648\u0631\u0634 \u062f\u0627\u0645 \u0648 \u0637\u06cc\u0648\u0631 \u0648 \u06af\u0644\u062e\u0627\u0646\u0647\u200c \u062f\u0627\u0631\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u0634\u063a\u0644\u200c\u0647\u0627\u06cc \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0647\u0633\u062a\u0646\u062f. \u0635\u0627\u062f\u0631\u0627\u062a \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0628\u0647 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u0647\u0645\u0633\u0627\u06cc\u0647 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062a\u0648\u0644\u06cc\u062f\u0627\u062a \u0627\u0631\u06af\u0627\u0646\u06cc\u06a9\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0633\u0648\u062f\u0622\u0648\u0631\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0622\u0641\u0631\u06cc\u0646\u0627\u0646 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B5%D9%86%D8%B9%D8%AA_%DA%AF%D8%B1%D8%AF%D8%B4%DA%AF%D8%B1%DB%8C_%D9%88_%D9%87%D8%AA%D9%84%D8%AF%D8%A7%D8%B1%DB%8C\"><\/span>\u0635\u0646\u0639\u062a \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0648 \u0647\u062a\u0644\u062f\u0627\u0631\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0648\u062c\u0648\u062f \u0628\u0646\u0627\u0647\u0627\u06cc \u062a\u0627\u0631\u06cc\u062e\u06cc \u0648 \u062c\u0627\u0630\u0628\u0647\u200c\u0647\u0627\u06cc \u0637\u0628\u06cc\u0639\u06cc \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u0635\u0646\u0639\u062a \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u067e\u062a\u0627\u0646\u0633\u06cc\u0644 \u0628\u0627\u0644\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0631\u0634\u062f \u062f\u0627\u0631\u062f. \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u0627\u0642\u0627\u0645\u062a\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0628\u0648\u0645\u200c\u06af\u0631\u062f\u06cc\u060c \u0631\u0633\u062a\u0648\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0633\u0646\u062a\u06cc\u060c \u06a9\u0627\u0641\u0647\u200c\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0648 \u062e\u062f\u0645\u0627\u062a \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc\u06cc \u062a\u0648\u0631\u060c \u0639\u06a9\u0627\u0633\u06cc \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639\u200c \u062f\u0633\u062a\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u062f\u0631 \u0627\u06cc\u0646 \u062d\u0648\u0632\u0647 \u0647\u0633\u062a\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u062f\u0631 \u0633\u0627\u062e\u062a \u0647\u062a\u0644\u200c\u0647\u0627\u06cc \u0644\u0648\u06a9\u0633 \u0648 \u0627\u0642\u0627\u0645\u062a\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0633\u0648\u062f \u062e\u0648\u0628\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D8%B4%D8%A7%D8%BA%D9%84_%D9%81%D9%86%DB%8C_%D9%88_%D9%85%D9%87%D9%86%D8%AF%D8%B3%DB%8C\"><\/span>\u0645\u0634\u0627\u063a\u0644 \u0641\u0646\u06cc \u0648 \u0645\u0647\u0646\u062f\u0633\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0645\u0634\u0627\u063a\u0644\u06cc \u0645\u0627\u0646\u0646\u062f \u0628\u0631\u0642\u200c\u06a9\u0627\u0631\u06cc\u060c \u062a\u0623\u0633\u06cc\u0633\u0627\u062a\u060c \u0645\u06a9\u0627\u0646\u06cc\u06a9\u06cc \u062e\u0648\u062f\u0631\u0648\u060c \u062a\u0639\u0645\u06cc\u0631\u0627\u062a \u0644\u0648\u0627\u0632\u0645 \u062e\u0627\u0646\u06af\u06cc \u0648 \u062c\u0648\u0634\u06a9\u0627\u0631\u06cc \u0635\u0646\u0639\u062a\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0647\u0633\u062a\u0646\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0635\u0646\u0639\u062a\u06cc \u0628\u0648\u062f\u0646 \u0627\u0633\u062a\u0627\u0646\u060c \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627 \u0648 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0628\u0647 \u062a\u06a9\u0646\u0633\u06cc\u0646\u200c\u0647\u0627\u06cc \u0645\u0627\u0647\u0631 \u0648 \u0645\u0647\u0646\u062f\u0633\u0627\u0646 \u0641\u0646\u06cc \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u0646\u062f. \u0627\u06cc\u0646 \u062f\u0633\u062a\u0647 \u0627\u0632 \u0645\u0634\u0627\u063a\u0644 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062a\u0642\u0627\u0636\u0627\u06cc \u0628\u0627\u0644\u0627 \u0648 \u0645\u0647\u0627\u0631\u062a\u200c\u0645\u062d\u0648\u0631 \u0628\u0648\u062f\u0646\u060c \u062f\u0631\u0622\u0645\u062f\u0647\u0627\u06cc \u062e\u0648\u0628\u06cc \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f \u0645\u062a\u062e\u0635\u0635 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%81%D8%B1%D9%88%D8%B4_%D9%88_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1%DB%8C%D8%A7%D8%A8%DB%8C\"><\/span>\u0641\u0631\u0648\u0634 \u0648 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0628\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0631\u0642\u0627\u0628\u062a \u062f\u0631 \u0628\u0627\u0632\u0627\u0631\u060c \u0645\u0634\u0627\u063a\u0644\u06cc \u0645\u0627\u0646\u0646\u062f \u0645\u062f\u06cc\u0631\u06cc\u062a \u0641\u0631\u0648\u0634\u060c \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644\u060c \u062a\u0628\u0644\u06cc\u063a\u0627\u062a \u0648 \u062a\u0648\u0644\u06cc\u062f \u0645\u062d\u062a\u0648\u0627 \u0628\u0647\u200c\u0634\u062f\u062a \u0645\u0648\u0631\u062f\u0646\u06cc\u0627\u0632 \u0647\u0633\u062a\u0646\u062f. \u06a9\u0633\u0628\u200c \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631 \u0641\u0636\u0627\u06cc \u0622\u0646\u0644\u0627\u06cc\u0646 \u0648 \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0641\u0639\u0627\u0644\u06cc\u062a \u0645\u0648\u0641\u0642\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631\u0622\u0645\u062f \u0628\u0627\u0644\u0627\u06cc\u06cc \u06a9\u0633\u0628 \u06a9\u0646\u0646\u062f.<\/span><\/p>\n<p>\u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f: <a href=\"https:\/\/karbord.io\/blog\/work-in-qazvin\/\" target=\"_blank\" rel=\"noopener\">\u0628\u0631\u0631\u0633\u06cc \u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0648 \u0635\u0646\u0627\u06cc\u0639 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646<\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%DA%86%D8%A7%D9%84%D8%B4%E2%80%8C%D9%87%D8%A7_%D9%88_%D9%85%D9%88%D8%A7%D9%86%D8%B9_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D9%82%D8%B2%D9%88%DB%8C%D9%86\"><\/span>\u0686\u0627\u0644\u0634\u200c\u0647\u0627 \u0648 \u0645\u0648\u0627\u0646\u0639 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0646\u06cc\u0632 \u0645\u0627\u0646\u0646\u062f \u062f\u06cc\u06af\u0631 \u0634\u0647\u0631\u0647\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0645\u0648\u0627\u0646\u0639 \u0632\u06cc\u0627\u062f\u06cc \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0627\u06cc\u0646 \u0645\u0648\u0627\u0646\u0639 \u062f\u0631 \u0627\u06a9\u062b\u0631 \u0645\u0648\u0627\u0642\u0639 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0647\u0633\u062a\u0646\u062f:<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D8%B4%DA%A9%D9%84%D8%A7%D8%AA_%D8%A8%DB%8C%DA%A9%D8%A7%D8%B1%DB%8C_%D9%88_%DA%A9%D9%85%D8%A8%D9%88%D8%AF_%D9%81%D8%B1%D8%B5%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%B4%D8%BA%D9%84%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%81%D8%A7%D8%B1%D8%BA%E2%80%8C%D8%A7%D9%84%D8%AA%D8%AD%D8%B5%DB%8C%D9%84%D8%A7%D9%86\"><\/span>\u0645\u0634\u06a9\u0644\u0627\u062a \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0648 \u06a9\u0645\u0628\u0648\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0628\u0631\u0627\u06cc \u0641\u0627\u0631\u063a\u200c\u0627\u0644\u062a\u062d\u0635\u06cc\u0644\u0627\u0646<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0632\u0631\u06af\u062a\u0631\u06cc\u0646 \u0686\u0627\u0644\u0634\u200c\u0647\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0641\u0627\u0631\u063a\u200c\u0627\u0644\u062a\u062d\u0635\u06cc\u0644\u0627\u0646 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u200c\u0647\u0627 \u0627\u0633\u062a. \u0628\u0627 \u0648\u062c\u0648\u062f \u0631\u0634\u062f \u062c\u0645\u0639\u06cc\u062a \u062a\u062d\u0635\u06cc\u0644\u200c\u06a9\u0631\u062f\u0647 \u0648 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u0648 \u062a\u062e\u0635\u0635\u06cc\u060c \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0641\u0627\u0631\u063a \u0627\u0644\u062a\u062d\u0635\u06cc\u0644 \u0646\u062a\u0648\u0627\u0646\u0633\u062a\u0647\u200c\u0627\u0646\u062f \u0634\u063a\u0644 \u0645\u0646\u0627\u0633\u0628 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0633\u0626\u0644\u0647 \u0628\u0647 \u062f\u0644\u0627\u06cc\u0644\u06cc \u0686\u0648\u0646 \u0639\u062f\u0645 \u062a\u0637\u0627\u0628\u0642 \u0645\u06cc\u0627\u0646 \u0631\u0634\u062a\u0647\u200c\u0647\u0627\u06cc \u062a\u062d\u0635\u06cc\u0644\u06cc \u0648 \u0646\u06cc\u0627\u0632 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631\u060c \u0645\u062d\u062f\u0648\u062f \u0628\u0648\u062f\u0646 \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u062f\u0631 \u0628\u0639\u0636\u06cc \u0627\u0632 \u0635\u0646\u0627\u06cc\u0639 \u062e\u0627\u0635 \u0648 \u0646\u0628\u0648\u062f \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0622\u0645\u0648\u0632\u0634\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u062c\u062f\u06cc\u062f \u0628\u0631\u0645\u06cc\u200c\u06af\u0631\u062f\u062f. \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647\u060c \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0641\u0627\u0631\u063a\u200c\u0627\u0644\u062a\u062d\u0635\u06cc\u0644\u0627\u0646 \u0628\u0647 \u0628\u06cc\u06a9\u0627\u0631\u06cc \u06cc\u0627 \u0645\u0634\u0627\u063a\u0644 \u063a\u06cc\u0631\u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u062a\u062d\u0635\u06cc\u0644\u0627\u062a \u062e\u0648\u062f \u062f\u0686\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0627\u0646\u06af\u06cc\u0632\u0647 \u062c\u0648\u0627\u0646\u0627\u0646 \u0628\u0631\u0627\u06cc \u0648\u0631\u0648\u062f \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0645\u0646\u062c\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0628\u0631 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0646\u0631\u062e \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0646\u06cc\u0632 \u062a\u0623\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0627\u0633\u062a.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D8%A3%D8%AB%DB%8C%D8%B1_%D8%B4%D8%B1%D8%A7%DB%8C%D8%B7_%D8%A7%D9%82%D8%AA%D8%B5%D8%A7%D8%AF%DB%8C_%DA%A9%D8%B4%D9%88%D8%B1_%D8%A8%D8%B1_%DA%A9%D8%B3%D8%A8%E2%80%8C_%D9%88_%DA%A9%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D9%85%D8%AD%D9%84%DB%8C\"><\/span>\u062a\u0623\u062b\u06cc\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u06a9\u0634\u0648\u0631 \u0628\u0631 \u06a9\u0633\u0628\u200c \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u062d\u0644\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0634\u0631\u0627\u06cc\u0637 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u06a9\u0634\u0648\u0631\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0646\u0631\u062e \u0627\u0631\u0632\u060c \u062a\u0648\u0631\u0645 \u0648 \u062a\u062d\u0631\u06cc\u0645\u200c\u0647\u0627\u060c \u062a\u0623\u062b\u06cc\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645 \u0628\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u062f\u0627\u0631\u062f. \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0633\u0628\u200c \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u062d\u0644\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u060c \u06a9\u0627\u0647\u0634 \u0642\u062f\u0631\u062a \u062e\u0631\u06cc\u062f \u0645\u0631\u062f\u0645 \u0648 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u200c\u0647\u0627\u06cc \u0648\u0627\u0631\u062f\u0627\u062a \u0648 \u0635\u0627\u062f\u0631\u0627\u062a \u0628\u0627 \u0645\u0634\u06a9\u0644\u0627\u062a \u062c\u062f\u06cc \u0631\u0648 \u0628\u0647\u200c \u0631\u0648 \u0647\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0634\u06a9\u0644\u0627\u062a \u0645\u0648\u062c\u0628 \u0627\u0641\u062a \u062a\u0648\u0644\u06cc\u062f \u0648 \u06a9\u0627\u0647\u0634 \u0633\u0648\u062f\u0622\u0648\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647\u060c \u0627\u0634\u062a\u063a\u0627\u0644 \u062f\u0631 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062a\u062d\u062a \u062a\u0623\u062b\u06cc\u0631 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u0628\u0647 \u0648\u06cc\u0698\u0647 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u06a9\u0648\u0686\u06a9 \u0648 \u0645\u062a\u0648\u0633\u0637 \u06a9\u0647 \u0628\u0647 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0648 \u0645\u0646\u0627\u0628\u0639 \u062e\u0627\u0631\u062c\u06cc \u0648\u0627\u0628\u0633\u062a\u0647 \u0647\u0633\u062a\u0646\u062f\u060c \u0634\u0631\u0627\u06cc\u0637 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u06a9\u0634\u0648\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0647\u062f\u06cc\u062f\u06cc \u0628\u0631\u0627\u06cc \u062a\u0648\u0633\u0639\u0647 \u0648 \u0631\u0648\u0646\u0642 \u06a9\u0633\u0628\u200c \u0648 \u06a9\u0627\u0631 \u0628\u0627\u0634\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646\u060c \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u06a9\u0645\u0628\u0648\u062f \u062b\u0628\u0627\u062a \u0645\u0627\u0644\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0648\u0627\u0646\u0639 \u0628\u0632\u0631\u06af \u062f\u0631 \u0645\u0633\u06cc\u0631 \u0627\u06cc\u062c\u0627\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u062c\u062f\u06cc\u062f \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0628\u0627\u0634\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%DA%A9%D9%85%D8%A8%D9%88%D8%AF_%D8%B3%D8%B1%D9%85%D8%A7%DB%8C%D9%87%E2%80%8C_%DA%AF%D8%B0%D8%A7%D8%B1%DB%8C_%D8%AF%D8%B1_%D8%A8%D8%B1%D8%AE%DB%8C_%D8%A8%D8%AE%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D9%82%D8%AA%D8%B5%D8%A7%D8%AF%DB%8C\"><\/span>\u06a9\u0645\u0628\u0648\u062f \u0633\u0631\u0645\u0627\u06cc\u0647\u200c \u06af\u0630\u0627\u0631\u06cc \u062f\u0631 \u0628\u0631\u062e\u06cc \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0628\u0627 \u0648\u062c\u0648\u062f \u0638\u0631\u0641\u06cc\u062a\u200c\u0647\u0627\u06cc \u0639\u0638\u06cc\u0645 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u060c \u0647\u0646\u0648\u0632 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u06a9\u0627\u0641\u06cc \u062f\u0631 \u0628\u0631\u062e\u06cc \u0628\u062e\u0634\u200c\u0647\u0627 \u0645\u0634\u0627\u0647\u062f\u0647 \u0646\u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u062e\u0634\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u0635\u0646\u0627\u06cc\u0639 \u0646\u0648\u0622\u0648\u0631\u0627\u0646\u0647\u060c \u06af\u0631\u062f\u0634\u06af\u0631\u06cc\u060c \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0627\u0631\u06af\u0627\u0646\u06cc\u06a9 \u0648 \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0628\u0647 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u062e\u0627\u0631\u062c\u06cc \u0648 \u062f\u0627\u062e\u0644\u06cc \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u0646\u062f \u062a\u0627 \u0628\u0647 \u062a\u0648\u0633\u0639\u0647 \u062e\u0648\u062f \u0627\u062f\u0627\u0645\u0647 \u062f\u0647\u0646\u062f. \u0646\u0628\u0648\u062f \u062d\u0645\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc \u0644\u0627\u0632\u0645 \u0627\u0632 \u062f\u0648\u0644\u062a\u060c \u0645\u0634\u06a9\u0644\u0627\u062a \u062f\u0631 \u062a\u0623\u0645\u06cc\u0646 \u0645\u0627\u0644\u06cc \u0648 \u0639\u062f\u0645 \u0622\u0634\u0646\u0627\u06cc\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0628\u0627 \u067e\u062a\u0627\u0646\u0633\u06cc\u0644\u200c\u0647\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc \u0627\u0633\u062a\u0627\u0646 \u0627\u0632 \u062c\u0645\u0644\u0647 \u062f\u0644\u0627\u06cc\u0644 \u0627\u06cc\u0646 \u06a9\u0645\u0628\u0648\u062f \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0647\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u06a9\u0645\u0628\u0648\u062f \u0633\u0631\u0645\u0627\u06cc\u0647\u200c \u06af\u0630\u0627\u0631\u06cc \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u062c\u062f\u06cc\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0631\u0634\u062f \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0634\u062a\u063a\u0627\u0644 \u06a9\u0645\u06a9 \u06a9\u0646\u0646\u062f\u060c \u0628\u0647 \u062a\u0639\u0648\u06cc\u0642 \u0628\u06cc\u0641\u062a\u0646\u062f \u06cc\u0627 \u0627\u0632 \u062f\u0633\u062a \u0628\u0631\u0648\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646\u060c \u062d\u0645\u0627\u06cc\u062a \u0645\u0627\u0644\u06cc \u0648 \u062c\u0630\u0628 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0686\u0627\u0644\u0634 \u0627\u0633\u0627\u0633\u06cc \u0628\u0631\u0627\u06cc \u062a\u0648\u0633\u0639\u0647 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B1%D8%A7%D9%87%DA%A9%D8%A7%D8%B1%D9%87%D8%A7_%D9%88_%D9%BE%DB%8C%D8%B4%D9%86%D9%87%D8%A7%D8%AF%D9%87%D8%A7_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A8%D9%87%D8%A8%D9%88%D8%AF_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D9%82%D8%B2%D9%88%DB%8C%D9%86\"><\/span>\u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627 \u0648 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u0647\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631\u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0648 \u06cc\u0627 \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc \u062f\u06cc\u06af\u0631 \u0634\u0647\u0631\u0647\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0632\u06cc\u0631 \u0631\u0627 \u0628\u0647 \u06a9\u0627\u0631 \u06af\u0631\u0641\u062a:<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D9%88%D8%B3%D8%B9%D9%87_%D8%A7%D8%B3%D8%AA%D8%A7%D8%B1%D8%AA%D8%A7%D9%BE%E2%80%8C%D9%87%D8%A7_%D9%88_%D8%AD%D9%85%D8%A7%DB%8C%D8%AA_%D8%A7%D8%B2_%DA%A9%D8%A7%D8%B1%D8%A2%D9%81%D8%B1%DB%8C%D9%86%DB%8C\"><\/span>\u062a\u0648\u0633\u0639\u0647 \u0627\u0633\u062a\u0627\u0631\u062a\u0627\u067e\u200c\u0647\u0627 \u0648 \u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u06a9\u0627\u0631\u0622\u0641\u0631\u06cc\u0646\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0647\u0645 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u062a\u0648\u0633\u0639\u0647 \u0627\u0633\u062a\u0627\u0631\u062a\u0627\u067e\u200c\u0647\u0627 \u0648 \u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u06a9\u0627\u0631\u0622\u0641\u0631\u06cc\u0646\u06cc \u0627\u0633\u062a. \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u0627\u0633\u062a\u0627\u0631\u062a\u0627\u067e\u200c\u0647\u0627 \u062f\u0631 \u062d\u0648\u0632\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0627\u06cc\u062c\u0627\u062f \u0645\u0634\u0627\u063a\u0644 \u062c\u062f\u06cc\u062f \u0648 \u0631\u0648\u0646\u0642 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u0633\u062a\u0627\u0646 \u06a9\u0645\u06a9 \u06a9\u0646\u062f. \u062f\u0648\u0644\u062a \u0648 \u0646\u0647\u0627\u062f\u0647\u0627\u06cc \u0645\u062d\u0644\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 \u062a\u0633\u0647\u06cc\u0644 \u0634\u0631\u0627\u06cc\u0637 \u062a\u0623\u0633\u06cc\u0633 \u0627\u0633\u062a\u0627\u0631\u062a\u0627\u067e\u200c\u0647\u0627\u060c \u0627\u0639\u0637\u0627\u06cc \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u06a9\u0645\u200c\u0628\u0647\u0631\u0647 \u0648 \u0645\u0634\u0627\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc\u060c \u0627\u0632 \u06a9\u0627\u0631\u0622\u0641\u0631\u06cc\u0646\u0627\u0646 \u062d\u0645\u0627\u06cc\u062a \u06a9\u0646\u0646\u062f. \u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u06a9\u0627\u0631\u0622\u0641\u0631\u06cc\u0646\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0632\u0645\u06cc\u0646\u0647\u200c\u0633\u0627\u0632 \u0631\u0634\u062f \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u0627\u06cc\u062c\u0627\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u062c\u062f\u06cc\u062f \u0628\u0627\u0634\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D9%85%D9%87%D8%A7%D8%B1%D8%AA%E2%80%8C_%D8%A2%D9%85%D9%88%D8%B2%DB%8C_%D9%88_%D8%A2%D9%85%D9%88%D8%B2%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%81%D9%86%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%D9%88%D8%A7%D9%86%D8%A7%D9%86\"><\/span>\u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u0647\u0627\u0631\u062a\u200c \u0622\u0645\u0648\u0632\u06cc \u0648 \u0622\u0645\u0648\u0632\u0634\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u0628\u0631\u0627\u06cc \u062c\u0648\u0627\u0646\u0627\u0646<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0634\u062a\u063a\u0627\u0644 \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0622\u0645\u0648\u0632\u0634\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u0648 \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0648 \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0642\u0632\u0648\u06cc\u0646 \u0628\u0631\u0627\u06cc \u062c\u0648\u0627\u0646\u0627\u0646 \u0648 \u0641\u0627\u0631\u063a\u200c\u0627\u0644\u062a\u062d\u0635\u06cc\u0644\u0627\u0646 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u06af\u0633\u062a\u0631\u0634 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0646\u06cc\u0627\u0632 \u0631\u0648\u0632\u0627\u0641\u0632\u0648\u0646 \u0628\u0627\u0632\u0627\u0631 \u0628\u0647 \u0646\u06cc\u0631\u0648\u06cc \u06a9\u0627\u0631 \u0645\u0627\u0647\u0631 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u0645\u062e\u062a\u0644\u0641\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u0635\u0646\u0639\u062a\u060c \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a\u060c \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a\u060c \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u062f\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u0645\u0647\u0627\u0631\u062a\u200c\u0622\u0645\u0648\u0632\u06cc \u0648 \u0622\u0645\u0648\u0632\u0634\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u062f\u0631 \u0631\u0634\u062a\u0647\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u0648 \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0641\u0627\u0631\u063a\u200c\u0627\u0644\u062a\u062d\u0635\u06cc\u0644\u0627\u0646 \u06a9\u0645\u06a9 \u06a9\u0646\u062f \u062a\u0627 \u0634\u0627\u06cc\u0633\u062a\u06af\u06cc\u200c\u0647\u0627\u06cc \u0644\u0627\u0632\u0645 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0648\u0631\u0648\u062f \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u06a9\u0633\u0628 \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u062f\u0648\u0631\u0647\u200c\u0647\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0634\u0627\u0645\u0644 \u0622\u0645\u0648\u0632\u0634\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u0622\u0641\u0631\u06cc\u0646\u06cc\u060c \u0645\u062f\u06cc\u0631\u06cc\u062a\u060c \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0646\u0648\u06cc\u0633\u06cc\u060c \u0637\u0631\u0627\u062d\u06cc \u0648\u0628 \u0648 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u062f\u06cc\u06af\u0631 \u0628\u0627\u0634\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0647\u0645\u06a9\u0627\u0631\u06cc \u0628\u0627 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u0635\u0646\u0639\u062a\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a\u06cc \u0628\u0631\u0627\u06cc \u0622\u0645\u0648\u0632\u0634 \u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u0627\u0646 \u0628\u0647 \u0635\u0648\u0631\u062a \u0639\u0645\u0644\u06cc \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u06a9\u06cc\u0641\u06cc\u062a \u0645\u0647\u0627\u0631\u062a\u200c\u0622\u0645\u0648\u0632\u06cc \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B3%D8%B1%D9%85%D8%A7%DB%8C%D9%87%E2%80%8C%DA%AF%D8%B0%D8%A7%D8%B1%DB%8C_%D8%A8%DB%8C%D8%B4%D8%AA%D8%B1_%D8%AF%D8%B1_%D8%A8%D8%AE%D8%B4_%DA%AF%D8%B1%D8%AF%D8%B4%DA%AF%D8%B1%DB%8C_%D9%88_%D9%81%D9%86%D8%A7%D9%88%D8%B1%DB%8C_%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA\"><\/span>\u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631 \u0628\u062e\u0634 \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0648 \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0648 \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u067e\u062a\u0627\u0646\u0633\u06cc\u0644 \u0628\u0627\u0644\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u062f\u0627\u0631\u0646\u062f. \u0628\u0631\u0627\u06cc \u062a\u0642\u0648\u06cc\u062a \u0627\u06cc\u0646 \u0628\u062e\u0634\u200c\u0647\u0627\u060c \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0637\u0631\u0641 \u062f\u0648\u0644\u062a \u0648 \u0628\u062e\u0634 \u062e\u0635\u0648\u0635\u06cc \u0627\u0633\u062a. \u062f\u0631 \u062d\u0648\u0632\u0647 \u06af\u0631\u062f\u0634\u06af\u0631\u06cc\u060c \u062a\u0648\u0633\u0639\u0647 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a\u200c\u0647\u0627\u06cc \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0645\u0627\u0646\u0646\u062f \u0647\u062a\u0644\u200c\u0647\u0627\u060c \u0631\u0633\u062a\u0648\u0631\u0627\u0646\u200c\u0647\u0627\u060c \u0648 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u062a\u0641\u0631\u06cc\u062d\u06cc \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u062a\u0628\u0644\u06cc\u063a\u0627\u062a \u0648 \u0645\u0639\u0631\u0641\u06cc \u062c\u0627\u0630\u0628\u0647\u200c\u0647\u0627\u06cc \u062a\u0627\u0631\u06cc\u062e\u06cc \u0648 \u0637\u0628\u06cc\u0639\u06cc \u0642\u0632\u0648\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062c\u0630\u0628 \u06af\u0631\u062f\u0634\u06af\u0631\u0627\u0646 \u062f\u0627\u062e\u0644\u06cc \u0648 \u062e\u0627\u0631\u062c\u06cc \u06a9\u0645\u06a9 \u06a9\u0646\u062f. \u062f\u0631 \u0628\u062e\u0634 \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0646\u06cc\u0632\u060c \u0627\u06cc\u062c\u0627\u062f \u067e\u0627\u0631\u06a9\u200c\u0647\u0627\u06cc \u0641\u0646\u0627\u0648\u0631\u06cc\u060c \u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u0627\u0633\u062a\u0627\u0631\u062a\u0627\u067e\u200c\u0647\u0627\u06cc IT \u0648 \u0622\u0645\u0648\u0632\u0634 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0631\u0634\u062f \u0627\u06cc\u0646 \u0635\u0646\u0639\u062a \u0648 \u062a\u0648\u0633\u0639\u0647 \u0627\u0634\u062a\u063a\u0627\u0644 \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D9%81%D8%B1%D8%A7%D8%AF_%D8%AF%D8%B1_%D9%82%D8%B2%D9%88%DB%8C%D9%86_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D9%85%DB%8C%E2%80%8C%D8%AA%D9%88%D8%A7%D9%86%D9%86%D8%AF_%D9%81%D8%B1%D8%B5%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%B4%D8%BA%D9%84%DB%8C_%D8%B1%D8%A7_%D9%BE%DB%8C%D8%AF%D8%A7_%DA%A9%D9%86%D9%86%D8%AF%D8%9F\"><\/span>\u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0631\u0627 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f\u061f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0645\u0646\u0627\u0633\u0628 \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u0645\u062a\u0646\u0648\u0639\u06cc \u062c\u0633\u062a\u062c\u0648 \u06a9\u0646\u0646\u062f. \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0645\u062b\u0627\u0644\u060c \u062c\u0633\u062a\u062c\u0648 \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u06a9\u0627\u0631 \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0648 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u062f\u0631 \u0634\u0647\u0631 \u0635\u0646\u0639\u062a\u06cc \u0627\u0644\u0628\u0631\u0632 \u0642\u0632\u0648\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0641\u06cc\u062f\u06cc \u062f\u0631\u0628\u0627\u0631\u0647 \u0646\u062d\u0648\u0647 <a href=\"https:\/\/karbord.io\/jobs\/in-ghazvin-cities\" target=\"_blank\" rel=\"noopener\">\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0642\u0632\u0648\u06cc\u0646<\/a> \u0628\u0647 \u06a9\u0627\u0631\u062c\u0648\u06cc\u0627\u0646 \u0628\u062f\u0647\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0645\u0634\u0627\u063a\u0644 \u0633\u0627\u062f\u0647\u200c\u062a\u0631 \u0647\u0633\u062a\u0646\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0622\u06af\u0647\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0646\u0638\u06cc\u0631 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u06a9\u0627\u0631\u06af\u0631 \u0633\u0627\u062f\u0647 \u06a9\u0627\u0633\u067e\u06cc\u0646 \u0642\u0632\u0648\u06cc\u0646 \u0648 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u062f\u0631 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647 \u0642\u0632\u0648\u06cc\u0646 \u0628\u06af\u0631\u062f\u0646\u062f. \u062c\u0633\u062a \u0648 \u062c\u0648 \u062f\u0631 \u06a9\u0627\u0646\u0627\u0644 \u06a9\u0627\u0631\u06cc\u0627\u0628\u06cc \u0642\u0632\u0648\u06cc\u0646 \u0648 \u067e\u06cc\u062c \u06a9\u0627\u0631\u06cc\u0627\u0628\u06cc \u0642\u0632\u0648\u06cc\u0646 \u0648 \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u060c \u0631\u0627\u0647\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0646 \u0622\u06af\u0647\u06cc\u200c\u0647\u0627\u06cc \u0627\u0633\u062a\u062e\u062f\u0627\u0645\u06cc \u0648 \u062c\u0630\u0628 \u0646\u06cc\u0631\u0648 \u0628\u0647 \u062d\u0633\u0627\u0628 \u0645\u06cc\u200c\u0622\u06cc\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u0645\u062a\u0642\u0627\u0636\u06cc\u0627\u0646 \u0645\u0634\u0627\u063a\u0644 \u062a\u062e\u0635\u0635\u06cc \u0648 \u0633\u0646\u062a\u06cc\u060c \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0645\u062a\u0639\u062f\u062f\u06cc \u062f\u0631 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u061b \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0645\u062b\u0627\u0644\u060c \u0645\u0634\u0627\u063a\u0644\u06cc \u0645\u0627\u0646\u0646\u062f \u062d\u0633\u0627\u0628\u062f\u0627\u0631\u06cc \u0648 \u0641\u0631\u0648\u0634\u0646\u062f\u0647 \u062f\u0631 \u06af\u0631\u0648\u0647 \u0635\u0646\u0639\u062a\u06cc \u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u0627\u0633\u062a\u0627\u0646 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u0645\u0646\u0627\u0633\u0628 \u0647\u0633\u062a\u0646\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0634\u0647\u0631\u062f\u0627\u0631\u06cc \u0642\u0632\u0648\u06cc\u0646 \u0628\u0627 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0631\u0648\u06cc\u062f\u0627\u062f\u0647\u0627\u06cc\u06cc \u0645\u062b\u0644 \u0646\u0645\u0627\u06cc\u0634\u06af\u0627\u0647 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0633\u062a\u0631 \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0631\u0627\u06cc \u0627\u0634\u062a\u063a\u0627\u0644 \u0641\u0631\u0627\u0647\u0645 \u06a9\u0646\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0646\u0645\u0627\u06cc\u0634\u06af\u0627\u0647\u200c\u0647\u0627 \u0627\u0641\u0631\u0627\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u060c \u062d\u062a\u06cc \u0641\u0631\u0635\u062a \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u06a9\u0627\u0631\u06af\u0631 \u0633\u0627\u062f\u0647 \u062e\u0627\u0646\u0645 \u062f\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0628\u06af\u0631\u062f\u0646\u062f.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C\"><\/span>\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647\u200c \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0645\u062a\u0646\u0648\u0639 \u062f\u0631 \u062d\u0648\u0632\u0647\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc\u060c \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0648 \u06af\u0631\u062f\u0634\u06af\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u0648\u062c\u0648\u062f \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0641\u0627\u0631\u063a\u200c\u0627\u0644\u062a\u062d\u0635\u06cc\u0644\u0627\u0646\u060c \u062a\u0623\u062b\u06cc\u0631\u0627\u062a \u0634\u0631\u0627\u06cc\u0637 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u06a9\u0645\u0628\u0648\u062f \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc\u060c \u0647\u0645\u0686\u0646\u0627\u0646 \u067e\u062a\u0627\u0646\u0633\u06cc\u0644 \u0631\u0634\u062f \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f. \u0628\u0627 \u0627\u062a\u062e\u0627\u0630 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u0646\u0638\u06cc\u0631 \u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u0627\u0633\u062a\u0627\u0631\u062a\u0627\u067e\u200c\u0647\u0627\u060c \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u0647\u0627\u0631\u062a\u200c\u0622\u0645\u0648\u0632\u06cc \u062c\u0648\u0627\u0646\u0627\u0646\u060c \u062c\u0630\u0628 \u0633\u0631\u0645\u0627\u06cc\u0647 \u062f\u0631 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0646\u0648\u067e\u0627 \u0648 \u062a\u0642\u0648\u06cc\u062a \u0632\u06cc\u0631\u0633\u0627\u062e\u062a\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0646\u062a\u0638\u0627\u0631 \u062f\u0627\u0634\u062a \u06a9\u0647 \u0627\u06cc\u0646 \u0628\u0627\u0632\u0627\u0631 \u0628\u0647 \u062a\u0648\u0633\u0639\u0647\u200c \u062f\u0633\u062a \u06cc\u0627\u0628\u062f \u0648 \u0632\u0645\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0634\u062a\u063a\u0627\u0644 \u0648 \u0631\u0648\u0646\u0642 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u0633\u062a\u0627\u0646 \u0642\u0632\u0648\u06cc\u0646 \u0628\u0647\u0628\u0648\u062f \u06cc\u0627\u0628\u062f.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0648\u0642\u0639\u06cc\u062a \u062c\u063a\u0631\u0627\u0641\u06cc\u0627\u06cc\u06cc \u0645\u0646\u0627\u0633\u0628\u060c \u0646\u0632\u062f\u06cc\u06a9\u06cc \u0628\u0647 \u067e\u0627\u06cc\u062a\u062e\u062a\u060c \u0648\u062c\u0648\u062f \u0634\u0647\u0631\u06a9\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc \u0628\u0632\u0631\u06af \u0648 \u062a\u0648\u0644\u06cc\u062f\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0645\u062a\u0646\u0648\u0639\u060c \u0627\u0633\u062a\u0627\u0646 \u0642\u0632\u0648\u06cc\u0646 \u0631\u0627 \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0646\u0627\u0637\u0642 \u0628\u0627 \u067e\u062a\u0627\u0646\u0633\u06cc\u0644 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0628\u0627 \u0627\u06cc\u0646\u200c \u062d\u0627\u0644\u060c \u0645\u0627\u0646\u0646\u062f \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631\u060c \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0646\u06cc\u0632 \u0628\u0627 \u0686\u0627\u0644\u0634\u200c\u0647\u0627 \u0648 \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u062e\u0627\u0635 \u062e\u0648\u062f \u0631\u0648 \u0628\u0647\u200c \u0631\u0648 \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647\u060c \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0648\u0636\u0639\u06cc\u062a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-7846","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-cities-recruitment","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>\u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0648 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u0633\u062a\u0627\u0646 - \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f<\/title>\r\n<meta name=\"description\" content=\"\u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0648 \u0631\u0627\u0647 \u06a9\u0627\u0631 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u0648\u062f \u0648\u0636\u0639\u06cc\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0642\u0632\u0648\u06cc\u0646 \u0631\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u06cc\u062f.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/\" \/>\r\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"\u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0648 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u0633\u062a\u0627\u0646 - \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\" \/>\r\n<meta property=\"og:description\" content=\"\u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0648 \u0631\u0627\u0647 \u06a9\u0627\u0631 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u0648\u062f \u0648\u0636\u0639\u06cc\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0642\u0632\u0648\u06cc\u0646 \u0631\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u06cc\u062f.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/\" \/>\r\n<meta property=\"og:site_name\" content=\"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-02-24T16:15:41+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-02-25T07:49:37+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/02\/best-jobs-in-qazvin.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"300\" \/>\r\n\t<meta property=\"og:image:height\" content=\"200\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"karbord_admin\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"karbord_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\" \/>\n\t<meta name=\"twitter:data2\" content=\"45 \u062f\u0642\u06cc\u0642\u0647\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/\"},\"author\":{\"name\":\"karbord_admin\",\"@id\":\"https:\/\/karbord.io\/blog\/#\/schema\/person\/f1ae49387b03797cadd768465e47d402\"},\"headline\":\"\u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u061b \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u060c \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0648 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f\",\"datePublished\":\"2025-02-24T16:15:41+00:00\",\"dateModified\":\"2025-02-25T07:49:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/\"},\"wordCount\":8887,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/karbord.io\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/02\/best-jobs-in-qazvin.jpg\",\"articleSection\":[\"\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0634\u0647\u0631\u0647\u0627\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/\",\"url\":\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/\",\"name\":\"\u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0648 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u0633\u062a\u0627\u0646 - \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\",\"isPartOf\":{\"@id\":\"https:\/\/karbord.io\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/02\/best-jobs-in-qazvin.jpg\",\"datePublished\":\"2025-02-24T16:15:41+00:00\",\"dateModified\":\"2025-02-25T07:49:37+00:00\",\"description\":\"\u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0648 \u0631\u0627\u0647 \u06a9\u0627\u0631 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u0648\u062f \u0648\u0636\u0639\u06cc\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0642\u0632\u0648\u06cc\u0646 \u0631\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u06cc\u062f.\",\"breadcrumb\":{\"@id\":\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#primaryimage\",\"url\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/02\/best-jobs-in-qazvin.jpg\",\"contentUrl\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/02\/best-jobs-in-qazvin.jpg\",\"width\":300,\"height\":200,\"caption\":\"\u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\/\/karbord.io\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u061b \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u060c \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0648 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/karbord.io\/blog\/#website\",\"url\":\"https:\/\/karbord.io\/blog\/\",\"name\":\"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\",\"description\":\"\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06a9\u0627\u0631\u06cc\u0627\u0628\u06cc \u0648 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u0633\u06cc\u0631 \u0634\u063a\u0644\u06cc\",\"publisher\":{\"@id\":\"https:\/\/karbord.io\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/karbord.io\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/karbord.io\/blog\/#organization\",\"name\":\"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\",\"url\":\"https:\/\/karbord.io\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/karbord.io\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/01\/favicon.ico\",\"contentUrl\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/01\/favicon.ico\",\"width\":48,\"height\":48,\"caption\":\"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\"},\"image\":{\"@id\":\"https:\/\/karbord.io\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/karbord.io\/blog\/#\/schema\/person\/f1ae49387b03797cadd768465e47d402\",\"name\":\"karbord_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/karbord.io\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d4445745f0980f7e3cf3574521f499c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d4445745f0980f7e3cf3574521f499c0?s=96&d=mm&r=g\",\"caption\":\"karbord_admin\"},\"url\":\"https:\/\/karbord.io\/blog\/author\/karbord_admin\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0648 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u0633\u062a\u0627\u0646 - \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","description":"\u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0648 \u0631\u0627\u0647 \u06a9\u0627\u0631 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u0648\u062f \u0648\u0636\u0639\u06cc\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0642\u0632\u0648\u06cc\u0646 \u0631\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u06cc\u062f.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0648 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u0633\u062a\u0627\u0646 - \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","og_description":"\u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0648 \u0631\u0627\u0647 \u06a9\u0627\u0631 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u0648\u062f \u0648\u0636\u0639\u06cc\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0642\u0632\u0648\u06cc\u0646 \u0631\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u06cc\u062f.","og_url":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/","og_site_name":"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","article_published_time":"2025-02-24T16:15:41+00:00","article_modified_time":"2025-02-25T07:49:37+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/02\/best-jobs-in-qazvin.jpg","type":"image\/jpeg"}],"author":"karbord_admin","twitter_card":"summary_large_image","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a":"karbord_admin","\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646":"45 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#article","isPartOf":{"@id":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/"},"author":{"name":"karbord_admin","@id":"https:\/\/karbord.io\/blog\/#\/schema\/person\/f1ae49387b03797cadd768465e47d402"},"headline":"\u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u061b \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u060c \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0648 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f","datePublished":"2025-02-24T16:15:41+00:00","dateModified":"2025-02-25T07:49:37+00:00","mainEntityOfPage":{"@id":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/"},"wordCount":8887,"commentCount":0,"publisher":{"@id":"https:\/\/karbord.io\/blog\/#organization"},"image":{"@id":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#primaryimage"},"thumbnailUrl":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/02\/best-jobs-in-qazvin.jpg","articleSection":["\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0634\u0647\u0631\u0647\u0627"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/","url":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/","name":"\u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646 \u0648 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u0633\u062a\u0627\u0646 - \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","isPartOf":{"@id":"https:\/\/karbord.io\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#primaryimage"},"image":{"@id":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#primaryimage"},"thumbnailUrl":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/02\/best-jobs-in-qazvin.jpg","datePublished":"2025-02-24T16:15:41+00:00","dateModified":"2025-02-25T07:49:37+00:00","description":"\u0648\u0636\u0639\u06cc\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u060c \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646 \u0648 \u0631\u0627\u0647 \u06a9\u0627\u0631 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u0648\u062f \u0648\u0636\u0639\u06cc\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0642\u0632\u0648\u06cc\u0646 \u0631\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u06cc\u062f.","breadcrumb":{"@id":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#primaryimage","url":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/02\/best-jobs-in-qazvin.jpg","contentUrl":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/02\/best-jobs-in-qazvin.jpg","width":300,"height":200,"caption":"\u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646"},{"@type":"BreadcrumbList","@id":"https:\/\/karbord.io\/blog\/best-jobs-in-qazvin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/karbord.io\/blog\/"},{"@type":"ListItem","position":2,"name":"\u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0642\u0632\u0648\u06cc\u0646\u061b \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u060c \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0648 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f"}]},{"@type":"WebSite","@id":"https:\/\/karbord.io\/blog\/#website","url":"https:\/\/karbord.io\/blog\/","name":"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","description":"\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06a9\u0627\u0631\u06cc\u0627\u0628\u06cc \u0648 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u0633\u06cc\u0631 \u0634\u063a\u0644\u06cc","publisher":{"@id":"https:\/\/karbord.io\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/karbord.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/karbord.io\/blog\/#organization","name":"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","url":"https:\/\/karbord.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/karbord.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/01\/favicon.ico","contentUrl":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/01\/favicon.ico","width":48,"height":48,"caption":"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f"},"image":{"@id":"https:\/\/karbord.io\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/karbord.io\/blog\/#\/schema\/person\/f1ae49387b03797cadd768465e47d402","name":"karbord_admin","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/karbord.io\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d4445745f0980f7e3cf3574521f499c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4445745f0980f7e3cf3574521f499c0?s=96&d=mm&r=g","caption":"karbord_admin"},"url":"https:\/\/karbord.io\/blog\/author\/karbord_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/posts\/7846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/comments?post=7846"}],"version-history":[{"count":5,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/posts\/7846\/revisions"}],"predecessor-version":[{"id":7882,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/posts\/7846\/revisions\/7882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/media\/7847"}],"wp:attachment":[{"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/media?parent=7846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/categories?post=7846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/tags?post=7846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}