{"id":3412,"date":"2024-02-24T09:42:06","date_gmt":"2024-02-24T10:42:06","guid":{"rendered":"https:\/\/karbord.io\/blog\/?p=3412"},"modified":"2024-04-15T08:55:55","modified_gmt":"2024-04-15T08:55:55","slug":"operating-room-technician-job-introduction","status":"publish","type":"post","link":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/","title":{"rendered":"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\u061b \u0634\u0631\u062d \u0648\u0638\u0627\u06cc\u0641\u060c \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u062d\u0642\u0648\u0642"},"content":{"rendered":"<p>\u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0639\u0636\u0627\u06cc \u06a9\u0644\u06cc\u062f\u06cc \u06a9\u0627\u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u062f\u0631 \u0647\u0631 \u0628\u06cc\u0645\u0627\u0631\u0633\u062a\u0627\u0646 \u0627\u0633\u062a. \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a \u0634\u063a\u0644\u06cc \u0641\u0639\u0627\u0644\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u062f\u0631 \u0645\u0648\u0641\u0642\u06cc\u062a\u200c\u0622\u0645\u06cc\u0632 \u0628\u0648\u062f\u0646 \u0639\u0645\u0644\u200c\u0647\u0627\u06cc \u062c\u0631\u0627\u062d\u06cc \u0645\u062e\u062a\u0644\u0641 \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u062f\u0627\u0631\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0628\u0627 \u0627\u06cc\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a \u0634\u063a\u0644\u06cc \u0622\u0634\u0646\u0627 \u0634\u062f\u0647 \u0648 \u0648\u0638\u0627\u06cc\u0641\u060c \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u060c \u0645\u0632\u0627\u06cc\u0627 \u0648 \u0645\u0639\u0627\u06cc\u0628\u060c \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u0645\u06cc\u0632\u0627\u0646 \u062d\u0642\u0648\u0642 \u0622\u0646 \u0631\u0627 \u0645\u0648\u0631\u062f \u0628\u0631\u0631\u0633\u06cc \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u062f\u0647\u06cc\u0645.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_63 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\r\n<div class=\"ez-toc-title-container\">\r\n<p class=\"ez-toc-title \" >Table of Contents<\/p>\r\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\r\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D8%B4%D8%BA%D9%84_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84_%D8%AF%D8%B1_%DB%8C%DA%A9_%D9%86%DA%AF%D8%A7%D9%87\" title=\"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062f\u0631 \u06cc\u06a9 \u0646\u06af\u0627\u0647\">\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062f\u0631 \u06cc\u06a9 \u0646\u06af\u0627\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D8%B4%D8%B1%D8%AD_%D9%88%D8%B8%D8%A7%DB%8C%D9%81_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\" title=\"\u0634\u0631\u062d \u0648\u0638\u0627\u06cc\u0641 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\">\u0634\u0631\u062d \u0648\u0638\u0627\u06cc\u0641 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%DA%86%DA%AF%D9%88%D9%86%D9%87_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84_%D8%B4%D9%88%DB%8C%D9%85%D8%9F\" title=\"\u0686\u06af\u0648\u0646\u0647 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0634\u0648\u06cc\u0645\u061f\">\u0686\u06af\u0648\u0646\u0647 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0634\u0648\u06cc\u0645\u061f<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D8%B1%D8%B4%D8%AA%D9%87_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84_%D8%AF%D8%B1_%D8%AF%D8%A7%D9%86%D8%B4%DA%AF%D8%A7%D9%87\" title=\"\u0631\u0634\u062a\u0647 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062f\u0631 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\">\u0631\u0634\u062a\u0647 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062f\u0631 \u062f\u0627\u0646\u0634\u06af\u0627\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D9%85%D9%87%D8%A7%D8%B1%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%85%D9%88%D8%B1%D8%AF_%D9%86%DB%8C%D8%A7%D8%B2_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\" title=\"\u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\">\u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D9%85%D9%87%D8%A7%D8%B1%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%AA%D8%AE%D8%B5%D8%B5%DB%8C_%D9%85%D9%88%D8%B1%D8%AF_%D9%86%DB%8C%D8%A7%D8%B2_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\" title=\"\u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\">\u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D9%85%D9%87%D8%A7%D8%B1%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%86%D8%B1%D9%85_%D8%B6%D8%B1%D9%88%D8%B1%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\" title=\"\u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0646\u0631\u0645 \u0636\u0631\u0648\u0631\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\">\u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0646\u0631\u0645 \u0636\u0631\u0648\u0631\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D9%85%D8%B2%D8%A7%DB%8C%D8%A7_%D9%88_%D9%85%D8%B9%D8%A7%DB%8C%D8%A8_%D8%B4%D8%BA%D9%84_%D8%AA%DA%A9%D9%86%D8%B3%DB%8C%D9%86_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\" title=\"\u0645\u0632\u0627\u06cc\u0627 \u0648 \u0645\u0639\u0627\u06cc\u0628 \u0634\u063a\u0644 \u062a\u06a9\u0646\u0633\u06cc\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\">\u0645\u0632\u0627\u06cc\u0627 \u0648 \u0645\u0639\u0627\u06cc\u0628 \u0634\u063a\u0644 \u062a\u06a9\u0646\u0633\u06cc\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D8%B4%D8%BA%D9%84_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\" title=\"\u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\">\u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D9%85%D8%AD%DB%8C%D8%B7_%DA%A9%D8%A7%D8%B1_%D8%AA%DA%A9%D9%86%D8%B3%DB%8C%D9%86%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\" title=\"\u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631 \u062a\u06a9\u0646\u0633\u06cc\u0646\u200c\u0647\u0627\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\">\u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631 \u062a\u06a9\u0646\u0633\u06cc\u0646\u200c\u0647\u0627\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D8%AD%D9%88%D8%B2%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%AA%D8%AE%D8%B5%D8%B5%DB%8C_%D8%B4%D8%BA%D9%84_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\" title=\"\u062d\u0648\u0632\u0647\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\">\u062d\u0648\u0632\u0647\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D8%AD%D9%82%D9%88%D9%82_%D8%AA%DA%A9%D9%86%D8%B3%DB%8C%D9%86_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84_1402\" title=\"\u062d\u0642\u0648\u0642 \u062a\u06a9\u0646\u0633\u06cc\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 1402\">\u062d\u0642\u0648\u0642 \u062a\u06a9\u0646\u0633\u06cc\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 1402<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C\" title=\"\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc\">\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\r\n<h2><span class=\"ez-toc-section\" id=\"%D8%B4%D8%BA%D9%84_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84_%D8%AF%D8%B1_%DB%8C%DA%A9_%D9%86%DA%AF%D8%A7%D9%87\"><\/span>\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062f\u0631 \u06cc\u06a9 \u0646\u06af\u0627\u0647<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3415\" src=\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician-1.jpg\" alt=\"\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\" width=\"900\" height=\"600\" srcset=\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician-1.jpg 900w, https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician-1-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/p>\n<p>\u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06a9\u0647 \u0628\u0627 \u0639\u0646\u0648\u0627\u0646 <a href=\"https:\/\/karbord.io\/jobs\/surgery-coordinator\">\u062a\u06a9\u0646\u0633\u06cc\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/a> \u0646\u06cc\u0632 \u0634\u0646\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0639\u0636\u0627\u06cc \u06a9\u0627\u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u062f\u0633\u062a\u06cc\u0627\u0631 \u062c\u0631\u0627\u062d\u060c \u0647\u0648\u0634\u0628\u0631\u060c \u067e\u0631\u0633\u062a\u0627\u0631\u060c \u062c\u0631\u0627\u062d \u0648&#8230; \u062f\u0631 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u062e\u062f\u0645\u062a\u200c\u0631\u0633\u0627\u0646\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0628\u0637\u0648\u0631 \u06a9\u0644\u06cc\u060c \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a \u0634\u063a\u0644\u06cc \u0641\u0639\u0627\u0644 \u0647\u0633\u062a\u0646\u062f\u060c \u0648\u0638\u0627\u06cc\u0641 \u0645\u062e\u062a\u0644\u0641\u06cc \u0631\u0627 \u0628\u0631 \u0639\u0647\u062f\u0647 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f \u0648 \u062f\u0631 \u0633\u0647 \u0645\u0631\u062d\u0644\u0647 \u067e\u06cc\u0634\u060c \u062d\u06cc\u0646 \u0648 \u067e\u0633 \u0627\u0632 \u0639\u0645\u0644 \u0628\u0647 \u062a\u06cc\u0645 \u062c\u0631\u0627\u062d\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u062a\u0627 \u0645\u062d\u06cc\u0637\u06cc \u0627\u06cc\u0645\u0646 \u0648 \u0636\u062f\u0639\u0641\u0648\u0646\u06cc \u0634\u062f\u0647 \u0628\u0631\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0641\u0631\u0627\u0647\u0645 \u0634\u0648\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B4%D8%B1%D8%AD_%D9%88%D8%B8%D8%A7%DB%8C%D9%81_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\"><\/span>\u0634\u0631\u062d \u0648\u0638\u0627\u06cc\u0641 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u067e\u06cc\u0634\u200c\u062a\u0631 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f\u06cc\u0645\u060c \u062a\u06a9\u0646\u0633\u06cc\u0646\u200c\u0647\u0627\u06cc \u062c\u0631\u0627\u062d\u06cc \u062f\u0631 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0628\u0627 \u062c\u0631\u0627\u062d\u0627\u0646\u060c \u0645\u062a\u062e\u0635\u0635\u0627\u0646 \u0628\u06cc\u0647\u0648\u0634\u06cc \u0648 \u067e\u0631\u0633\u062a\u0627\u0631\u0627\u0646 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0648\u0638\u0627\u06cc\u0641 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0633\u0647 \u0645\u0631\u062d\u0644\u0647 \u062a\u0642\u0633\u06cc\u0645 \u06a9\u0631\u062f: \u0642\u0628\u0644 \u0627\u0632 \u0639\u0645\u0644 \u062c\u0631\u0627\u062d\u06cc\u060c \u062f\u0631 \u062d\u06cc\u0646 \u0639\u0645\u0644 \u0648 \u0628\u0639\u062f \u0627\u0632 \u0622\u0646.<\/p>\n<p><strong>\u0642\u0628\u0644 \u0627\u0632 \u0639\u0645\u0644<\/strong>\u060c \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u200c\u0647\u0627\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0628\u0631 \u0631\u0648\u06cc \u0636\u062f\u0639\u0641\u0648\u0646\u06cc \u06a9\u0631\u062f\u0646 \u0648 \u0622\u0645\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u0627\u062a\u0627\u0642 \u0648 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u062c\u0631\u0627\u062d\u06cc \u062a\u0645\u0631\u06a9\u0632 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0634\u0627\u0645\u0644 \u0648\u0638\u0627\u06cc\u0641 \u0632\u06cc\u0631 \u0627\u0633\u062a:<\/p>\n<ul>\n<li>\u0636\u062f\u0639\u0641\u0648\u0646\u06cc \u06a9\u0631\u062f\u0646 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0648 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/li>\n<li>\u06a9\u0645\u06a9 \u0628\u0647 \u0622\u0645\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u0628\u06cc\u0645\u0627\u0631 \u0628\u0631\u0627\u06cc \u062c\u0631\u0627\u062d\u06cc<\/li>\n<li>\u062c\u0645\u0639 \u0622\u0648\u0631\u06cc\u060c \u0634\u0645\u0627\u0631\u0634 \u0648 \u0686\u06cc\u062f\u0645\u0627\u0646 \u0648\u0633\u0627\u06cc\u0644 \u0648 \u0627\u0628\u0632\u0627\u0631 \u062c\u0631\u0627\u062d\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0628\u0631\u0627\u06cc \u0639\u0645\u0644<\/li>\n<\/ul>\n<p><strong>\u062f\u0631 \u0637\u0648\u0644 \u062c\u0631\u0627\u062d\u06cc<\/strong>\u060c \u062a\u06a9\u0646\u0633\u06cc\u0646\u200c\u0647\u0627\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0648\u0638\u0627\u06cc\u0641 \u0645\u0647\u0645 \u0645\u062e\u062a\u0644\u0641\u06cc \u062f\u0627\u0631\u0646\u062f:<\/p>\n<ul>\n<li>\u0627\u0633\u062a\u0631\u06cc\u0644 \u0646\u06af\u0647 \u062f\u0627\u0634\u062a\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/li>\n<li>\u0627\u0646\u062a\u0642\u0627\u0644 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u062c\u0631\u0627\u062d\u06cc \u0628\u0647 \u062c\u0631\u0627\u062d \u0648 \u062f\u0633\u062a\u06cc\u0627\u0631 \u062c\u0631\u0627\u062d<\/li>\n<li>\u06a9\u0645\u06a9 \u0628\u0647 \u062c\u0645\u0639 \u06a9\u0631\u062f\u0646 \u0628\u0627\u0641\u062a\u200c\u0647\u0627<\/li>\n<\/ul>\n<p><strong>\u067e\u0633 \u0627\u0632 \u062c\u0631\u0627\u062d\u06cc<\/strong>\u060c \u062a\u06a9\u0646\u0633\u06cc\u0646\u200c\u0647\u0627\u06cc \u062c\u0631\u0627\u062d\u06cc \u062f\u0631 \u062a\u06a9\u0645\u06cc\u0644 \u0641\u0631\u0622\u06cc\u0646\u062f \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0647 \u0648 \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0631\u0627 \u0628\u0631 \u0639\u0647\u062f\u0647 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f:<\/p>\n<ul>\n<li>\u0634\u0645\u0627\u0631\u0634 \u0648 \u062a\u0645\u06cc\u0632 \u06a9\u0631\u062f\u0646 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u062f\u0647 \u062f\u0631 \u0637\u0648\u0644 \u062c\u0631\u0627\u062d\u06cc<\/li>\n<li>\u067e\u0627\u0646\u0633\u0645\u0627\u0646 \u06a9\u0631\u062f\u0646 \u0645\u062d\u0644 \u062c\u0631\u0627\u062d\u06cc<\/li>\n<li>\u062f\u0648\u0631 \u0627\u0646\u062f\u0627\u062e\u062a\u0646 \u0633\u0648\u0632\u0646\u060c \u06af\u0627\u0632 \u0648 \u0645\u0648\u0627\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u062f\u0647<\/li>\n<li>\u062d\u0641\u0638 \u0645\u062d\u06cc\u0637 \u0627\u0633\u062a\u0631\u06cc\u0644 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0628\u06cc\u0645\u0627\u0631 \u0628\u0647 \u0627\u062a\u0627\u0642 \u0631\u06cc\u06a9\u0627\u0648\u0631\u06cc \u0628\u0631\u062f\u0647 \u0634\u0648\u062f<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%DA%86%DA%AF%D9%88%D9%86%D9%87_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84_%D8%B4%D9%88%DB%8C%D9%85%D8%9F\"><\/span>\u0686\u06af\u0648\u0646\u0647 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0634\u0648\u06cc\u0645\u061f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0645\u0634\u063a\u0648\u0644 \u06a9\u0627\u0631 \u0634\u0648\u06cc\u062f\u060c \u0628\u0627\u06cc\u062f \u0627\u0628\u062a\u062f\u0627 \u062f\u0631 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0634\u062a\u0647 \u062a\u062d\u0635\u06cc\u0644 \u06a9\u0646\u06cc\u062f. \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0634\u062a\u0647\u200c\u0647\u0627\u06cc \u067e\u0631\u0637\u0631\u0641\u062f\u0627\u0631 \u0628\u06cc\u0646 \u062f\u0627\u0646\u0634\u200c\u0622\u0645\u0648\u0632\u0627\u0646 \u062a\u062c\u0631\u0628\u06cc \u0627\u0633\u062a \u0648 \u0634\u0645\u0627 \u0628\u0627 \u0634\u0631\u06a9\u062a \u062f\u0631 \u06a9\u0646\u06a9\u0648\u0631 \u0633\u0631\u0627\u0633\u0631\u06cc \u0648 \u06a9\u0633\u0628 \u0631\u062a\u0628\u0647 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u062a\u062d\u0635\u06cc\u0644 \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0634\u062a\u0647 \u0631\u0627 \u0622\u063a\u0627\u0632 \u06a9\u0646\u06cc\u062f. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0622\u0646\u060c \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0634\u063a\u0644 \u0639\u0645\u0644\u06a9\u0631\u062f \u0645\u0648\u0641\u0642\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u060c\u200c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0631\u062e\u06cc \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u0648 \u0646\u0631\u0645 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0622\u0646 \u0631\u0627 \u0628\u06cc\u0627\u0645\u0648\u0632\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B1%D8%B4%D8%AA%D9%87_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84_%D8%AF%D8%B1_%D8%AF%D8%A7%D9%86%D8%B4%DA%AF%D8%A7%D9%87\"><\/span>\u0631\u0634\u062a\u0647 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062f\u0631 \u062f\u0627\u0646\u0634\u06af\u0627\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u067e\u0633 \u0627\u0632 \u0642\u0628\u0648\u0644\u06cc \u062f\u0631 \u0631\u0634\u062a\u0647 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062f\u0631 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0622\u0632\u0627\u062f \u06cc\u0627 \u062f\u0648\u0644\u062a\u06cc\u060c \u0628\u0627\u06cc\u062f \u0648\u0627\u062d\u062f\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u06cc\u0646 \u0631\u0634\u062a\u0647 \u0631\u0627 \u067e\u0634\u062a \u0633\u0631 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f. \u0628\u0631\u062e\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0648\u0627\u062d\u062f\u0647\u0627 \u062a\u0626\u0648\u0631\u06cc \u0647\u0633\u062a\u0646\u062f \u0648 \u0628\u0631\u062e\u06cc \u062f\u06cc\u06af\u0631\u060c \u0648\u0627\u062d\u062f\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc \u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u06cc. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0644\u06cc\u0633\u062a \u06a9\u0648\u062a\u0627\u0647\u06cc \u0627\u0632 \u0628\u0631\u062e\u06cc \u062f\u0631\u0648\u0633\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0634\u062a\u0647 \u062a\u062f\u0631\u06cc\u0633 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0622\u0648\u0631\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a:<\/p>\n<ul>\n<li>\u062f\u0627\u0631\u0648\u0634\u0646\u0627\u0633\u06cc<\/li>\n<li>\u0627\u06cc\u0645\u0648\u0646\u0648\u0644\u0648\u0698\u06cc<\/li>\n<li>\u062e\u0648\u0646\u200c\u0634\u0646\u0627\u0633\u06cc \u0648 \u0627\u0646\u062a\u0642\u0627\u0644 \u062e\u0648\u0646<\/li>\n<li>\u0627\u0635\u0648\u0644 \u0627\u0633\u062a\u0631\u06cc\u0644\u06cc\u0632\u0627\u0633\u06cc\u0648\u0646 \u0648 \u0636\u062f\u0639\u0641\u0648\u0646\u06cc<\/li>\n<li>\u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0627\u0631\u062a\u0648\u067e\u062f\u06cc \u0648 \u0645\u0631\u0627\u0642\u0628\u062a\u200c\u0647\u0627\u06cc \u0622\u0646<\/li>\n<li>\u0641\u0648\u0631\u06cc\u062a\u200c\u0647\u0627\u06cc \u067e\u0632\u0634\u06a9\u06cc<\/li>\n<li>\u0627\u062e\u0644\u0627\u0642 \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u062f\u0631 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/li>\n<li>\u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0627\u062d\u06cc\u0627\u06cc \u0642\u0644\u0628\u06cc \u0631\u06cc\u0648\u06cc \u0648 \u0627\u0635\u0648\u0644 \u0645\u0631\u0627\u0642\u0628\u062a\u200c\u0647\u0627\u06cc \u0622\u0646<\/li>\n<li>\u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0686\u0634\u0645 \u0648 \u0645\u0631\u0627\u0642\u0628\u062a\u200c\u0647\u0627\u06cc \u0622\u0646<\/li>\n<li>\u0628\u0647\u062f\u0627\u0634\u062a \u0631\u0648\u0627\u0646 \u062f\u0631 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/li>\n<li>\u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0639\u0645\u0648\u0645\u06cc<\/li>\n<li>\u0628\u0627\u06a9\u062a\u0631\u06cc\u0648\u0644\u0648\u0698\u06cc \u0648 \u0627\u0646\u06af\u0644\u200c\u0634\u0646\u0627\u0633\u06cc<\/li>\n<\/ul>\n<p>\u062f\u0631\u0648\u0633 \u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u06cc \u06a9\u0647 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u0627\u0646 \u0627\u06cc\u0646 \u0631\u0634\u062a\u0647 \u0628\u0627\u06cc\u062f \u067e\u0634\u062a \u0633\u0631 \u0628\u06af\u0630\u0627\u0631\u0646\u062f \u0646\u06cc\u0632 \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/p>\n<ul>\n<li>\u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u06cc \u062f\u0631 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0627\u0648\u0631\u0698\u0627\u0646\u0633<\/li>\n<li>\u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u06cc \u0628\u062e\u0634 \u0627\u0633\u062a\u0631\u06cc\u0644 \u0645\u0631\u06a9\u0632\u06cc<\/li>\n<li>\u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0627\u062d\u06cc\u0627\u06cc \u0642\u0644\u0628\u06cc \u0631\u06cc\u0648\u06cc<\/li>\n<li>\u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u06cc \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0628\u0627\u0644\u06cc\u0646\u06cc<\/li>\n<li>\u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u06cc \u0627\u0635\u0648\u0644 \u0648 \u0641\u0646\u0648\u0646 \u0639\u0645\u0644\u06a9\u0631\u062f \u0641\u0631\u062f \u0633\u06cc\u0627\u0631<\/li>\n<li>\u0627\u0635\u0648\u0644 \u0645\u0631\u0627\u0642\u0628\u062a \u062f\u0631 \u0627\u062a\u0627\u0642 \u0628\u0647\u0628\u0648\u062f\u06cc<\/li>\n<li>\u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u06cc \u0631\u0641\u062a\u0627\u0631 \u062f\u0631 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/li>\n<li>\u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u06cc \u062a\u06a9\u0646\u06cc\u06a9 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/li>\n<\/ul>\n<p>\u0645\u0637\u0627\u0644\u0628 \u0645\u0631\u062a\u0628\u0637: <a href=\"https:\/\/karbord.io\/blog\/medical-doctor-job-introduction\/\">\u0645\u0639\u0631\u0641\u06cc \u0634\u063a\u0644 \u067e\u0632\u0634\u06a9\u06cc \u0627\u0632 \u062a\u062d\u0635\u06cc\u0644 \u062a\u0627 \u0648\u0631\u0648\u062f \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631<\/a><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D9%87%D8%A7%D8%B1%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%85%D9%88%D8%B1%D8%AF_%D9%86%DB%8C%D8%A7%D8%B2_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\"><\/span>\u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3416\" src=\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician-2.jpg\" alt=\"\u0645\u0647\u0627\u0631\u062a \u0647\u0627\u06cc \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\" width=\"900\" height=\"600\" srcset=\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician-2.jpg 900w, https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician-2-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/p>\n<p>\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u062f\u0627\u0634\u062a\u0646 \u062a\u062d\u0635\u06cc\u0644\u0627\u062a \u0645\u0646\u0627\u0633\u0628\u060c \u06a9\u0627\u0631\u0641\u0631\u0645\u0627\u06cc\u0627\u0646 \u0647\u0646\u06af\u0627\u0645 <a href=\"https:\/\/karbord.io\/jobs\/surgery-coordinator\">\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/a> \u062f\u0631 \u0634\u0631\u06a9\u062a \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u067e\u0632\u0634\u06a9\u06cc \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u0633\u062a\u0627\u0646\u060c \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0627\u0641\u0631\u0627\u062f\u06cc \u0628\u0627 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u0648 \u0646\u0631\u0645 \u0645\u062a\u0641\u0627\u0648\u062a \u0647\u0633\u062a\u0646\u062f. \u0627\u063a\u0644\u0628 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u0631\u0627 \u062f\u0631 \u0637\u0648\u0644 \u062a\u062d\u0635\u06cc\u0644 \u0622\u0645\u0648\u062e\u062a\u0647 \u0648 \u062f\u0631 \u062f\u0648\u0631\u0627\u0646 \u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u06cc \u0628\u0647 \u062a\u0642\u0648\u06cc\u062a \u0622\u0646\u200c\u0647\u0627 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u062f. \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0646\u0631\u0645 \u0631\u0627 \u0646\u06cc\u0632 \u0645\u0639\u0645\u0648\u0644\u0627 \u062f\u0631 \u0645\u0631\u0627\u062d\u0644 \u0645\u062e\u062a\u0644\u0641 \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0622\u0645\u0648\u062e\u062a\u0647 \u0648 \u062d\u0627\u0644\u0627 \u0628\u0627\u06cc\u062f \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u06a9\u0627\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f. \u0627\u06cc\u0646 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627 \u0628\u0647 \u0628\u0631\u0642\u0631\u0627\u0631\u06cc \u0627\u0631\u062a\u0628\u0627\u0637 \u0645\u0648\u062b\u0631 \u0628\u0627 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0648 \u0627\u0646\u062c\u0627\u0645 \u0635\u062d\u06cc\u062d \u0648\u0638\u0627\u06cc\u0641 \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D9%85%D9%87%D8%A7%D8%B1%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%AA%D8%AE%D8%B5%D8%B5%DB%8C_%D9%85%D9%88%D8%B1%D8%AF_%D9%86%DB%8C%D8%A7%D8%B2_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\"><\/span>\u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li>\u062f\u0627\u0646\u0634 \u06a9\u0627\u0641\u06cc \u062f\u0631\u0628\u0627\u0631\u0647 \u0639\u0644\u0627\u0626\u0645 \u062d\u06cc\u0627\u062a\u06cc \u0628\u06cc\u0645\u0627\u0631\u0627\u0646<\/li>\n<li>\u0646\u062d\u0648\u0647 \u0645\u0631\u0627\u0642\u0628\u062a \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0628\u0627 \u0648\u0636\u0639\u06cc\u062a \u062d\u0627\u062f<\/li>\n<li>\u062f\u0627\u0646\u0634 \u0641\u06cc\u0632\u06cc\u0648\u0644\u0648\u0698\u06cc<\/li>\n<li>\u062a\u06a9\u0646\u06cc\u06a9 \u0622\u0633\u067e\u062a\u06cc\u06a9<\/li>\n<li>\u0645\u0631\u0627\u0642\u0628\u062a\u200c\u0647\u0627\u06cc \u0627\u0648\u0644\u06cc\u0647<\/li>\n<li>\u06a9\u0627\u0631 \u062f\u0631 \u0648\u0627\u062d\u062f \u0645\u0631\u0627\u0642\u0628\u062a\u200c\u0647\u0627\u06cc \u0648\u06cc\u0698\u0647 (ICU)<\/li>\n<li>\u062f\u0627\u0646\u0634 \u0622\u0646\u0627\u062a\u0648\u0645\u06cc<\/li>\n<li>\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0627\u0635\u0637\u0644\u0627\u062d\u0627\u062a \u067e\u0632\u0634\u06a9\u06cc<\/li>\n<\/ul>\n<h4><span class=\"ez-toc-section\" id=\"%D9%85%D9%87%D8%A7%D8%B1%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%86%D8%B1%D9%85_%D8%B6%D8%B1%D9%88%D8%B1%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\"><\/span>\u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0646\u0631\u0645 \u0636\u0631\u0648\u0631\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li><strong>\u06a9\u0627\u0631 \u06af\u0631\u0648\u0647\u06cc: <\/strong>\u0647\u0631 \u0641\u0631\u062f\u06cc \u062f\u0631 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0646\u0642\u0634 \u0628\u0647\u200c\u062e\u0635\u0648\u0635\u06cc \u062f\u0627\u0631\u062f. \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u0627\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0646\u06cc\u0632 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0637\u0648\u0631 \u067e\u06cc\u0648\u0633\u062a\u0647 \u0628\u0627 \u067e\u0631\u0633\u062a\u0627\u0631\u0647\u0627\u060c \u062c\u0631\u0627\u062d\u200c\u0647\u0627\u060c \u0645\u062a\u062e\u0635\u0635\u0627\u0646 \u0628\u06cc\u0647\u0648\u0634\u06cc \u0648 \u0647\u0648\u0634\u0628\u0631\u0647\u0627 \u0647\u0645\u06a9\u0627\u0631\u06cc \u06a9\u0646\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646\u060c \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u06a9\u0627\u0631 \u06af\u0631\u0648\u0647\u06cc \u0627\u0632 \u0627\u0647\u0645\u06cc\u062a \u0628\u0627\u0644\u0627\u06cc\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0627\u0633\u062a.<\/li>\n<li><strong>\u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u0648 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0628\u06cc\u0646 \u0641\u0631\u062f\u06cc:<\/strong> \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0647\u0646\u06af\u0627\u0645 \u062c\u0631\u0627\u062d\u06cc \u0628\u0647 \u0635\u062d\u0628\u062a\u200c\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631\u0627\u0646 \u0628\u0647 \u062f\u0642\u062a \u06af\u0648\u0634 \u0641\u0631\u0627 \u062f\u0627\u062f\u0647 \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0632 \u0627\u0648 \u062e\u0648\u0627\u0633\u062a\u0647 \u0634\u062f\u0647 \u0631\u0627 \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0627\u0648 \u0627\u0632 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u06a9\u0644\u0627\u0645\u06cc \u062e\u0648\u062f \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u0642\u0627\u0644 \u067e\u06cc\u0627\u0645 \u0628\u0647 \u062c\u0631\u0627\u062d\u060c\u200c \u0628\u06cc\u0645\u0627\u0631 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0627\u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/li>\n<li><strong>\u062a\u0648\u062c\u0647 \u0628\u0647 \u062c\u0632\u0626\u06cc\u0627\u062a:<\/strong> \u062a\u06a9\u0646\u0633\u06cc\u0646\u200c\u0647\u0627\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0647\u0645\u0648\u0627\u0631\u0647 \u0628\u0627 \u06a9\u0645\u06a9 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u062f\u0631\u00a0\u062a\u0648\u062c\u0647 \u0628\u0647 \u062c\u0632\u0626\u064a\u0627\u062a\u060c \u0628\u0631\u0627\u06cc \u062d\u0641\u0638 \u0627\u06cc\u0645\u0646\u06cc \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0648 \u0627\u0639\u0636\u0627\u06cc \u06a9\u0627\u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u062a\u0644\u0627\u0634 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/li>\n<li><strong>\u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u06a9\u0627\u0631 \u062a\u062d\u062a \u0641\u0634\u0627\u0631:<\/strong> \u062f\u0631 \u062c\u0631\u0627\u062d\u06cc\u200c\u0647\u0627\u06cc \u0627\u0648\u0631\u0698\u0627\u0646\u0633\u06cc \u0627\u0632 \u0627\u0639\u0636\u0627\u06cc \u06a9\u0627\u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0627\u0646\u062a\u0638\u0627\u0631 \u0645\u06cc\u200c\u0631\u0648\u062f \u062e\u06cc\u0644\u06cc \u0633\u0631\u06cc\u0639 \u0628\u0647 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u0648\u0627\u06a9\u0646\u0634 \u0646\u0634\u0627\u0646 \u062f\u0647\u0646\u062f. \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u062a\u0645\u0627\u0645 \u0645\u0631\u0627\u062d\u0644 \u0639\u0645\u0644 \u062c\u0631\u0627\u062d\u06cc \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u067e\u06cc\u0634 \u0628\u0631\u0648\u062f\u060c \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u0627\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0628\u0627\u06cc\u062f \u0647\u0645\u0648\u0627\u0631\u0647 \u062a\u0645\u0631\u06a9\u0632 \u062e\u0648\u062f \u0631\u0627 \u062d\u0641\u0638 \u06a9\u0646\u0646\u062f.<\/li>\n<li><strong>\u0686\u0627\u0628\u06a9\u06cc:<\/strong> \u0633\u0631\u06cc\u0639 \u0648 \u0686\u0627\u0628\u06a9 \u0628\u0648\u062f\u0646 \u062a\u06a9\u0646\u0633\u06cc\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u0633\u0627\u06cc\u0631 \u0627\u0639\u0636\u0627\u06cc \u06a9\u0627\u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u0648\u0638\u0627\u06cc\u0641 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u0648 \u0628\u0627 \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0627\u062a\u0644\u0627\u0641 \u0648\u0642\u062a \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%D9%85%D8%B2%D8%A7%DB%8C%D8%A7_%D9%88_%D9%85%D8%B9%D8%A7%DB%8C%D8%A8_%D8%B4%D8%BA%D9%84_%D8%AA%DA%A9%D9%86%D8%B3%DB%8C%D9%86_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\"><\/span>\u0645\u0632\u0627\u06cc\u0627 \u0648 \u0645\u0639\u0627\u06cc\u0628 \u0634\u063a\u0644 \u062a\u06a9\u0646\u0633\u06cc\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0631\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0634\u063a\u0644 \u0622\u06cc\u0646\u062f\u0647 \u062e\u0648\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0628\u0627\u06cc\u062f \u0645\u0632\u0627\u06cc\u0627 \u0648 \u0645\u0639\u0627\u06cc\u0628 \u0622\u0646 \u0631\u0627 \u0628\u0627 \u062f\u0642\u062a \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u0646\u062f. \u0628\u06cc\u200c\u062a\u0648\u062c\u0647\u06cc \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0633\u0626\u0644\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627\u0639\u062b \u0634\u0648\u062f \u0622\u0646\u200c\u0647\u0627 \u0628\u0647 \u0645\u0631\u0648\u0631 \u0632\u0645\u0627\u0646 \u0627\u0646\u06af\u06cc\u0632\u0647 \u062e\u0648\u062f \u0627\u0632 \u06a9\u0627\u0631 \u06a9\u0631\u062f\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u062d\u0648\u0632\u0647 \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u0628\u062f\u0647\u0646\u062f.<\/p>\n<p>\u0628\u0631\u062e\u06cc \u0627\u0632 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u06cc\u0646 \u0634\u063a\u0644 \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/p>\n<ul>\n<li>\u0634\u063a\u0644 \u067e\u0631\u062f\u0631\u0622\u0645\u062f \u0628\u0627 \u0631\u0634\u062f \u0634\u063a\u0644\u06cc \u062b\u0627\u0628\u062a<\/li>\n<li>\u06a9\u0627\u0631 \u06a9\u0631\u062f\u0646 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0628\u062e\u0634\u06cc \u0627\u0632 \u06a9\u0627\u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u067e\u0633 \u0627\u0632 \u06f4 \u0633\u0627\u0644 \u062a\u062d\u0635\u06cc\u0644 \u062f\u0631 \u062f\u0627\u0646\u0634\u06af\u0627\u0647<\/li>\n<li>\u0627\u06cc\u062c\u0627\u062f \u062a\u063a\u06cc\u06cc\u0631 \u0645\u062b\u0628\u062a \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0648 \u0639\u0632\u06cc\u0632\u0627\u0646 \u0622\u0646\u200c\u0647\u0627<\/li>\n<li>\u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a<\/li>\n<\/ul>\n<p>\u0628\u0631\u062e\u06cc \u0627\u0632 \u0645\u0639\u0627\u06cc\u0628\u06cc \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0627\u06cc\u0646 \u0634\u063a\u0644 \u0628\u0627 \u0622\u0646\u200c\u0647\u0627 \u0645\u0648\u0627\u062c\u0647 \u0634\u0648\u06cc\u062f \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/p>\n<ul>\n<li>\u0634\u06cc\u0641\u062a\u200c\u0647\u0627\u06cc \u0637\u0648\u0644\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u0622\u0646\u200c\u0647\u0627 \u062a\u06a9\u0646\u0633\u06cc\u0646 \u0645\u062c\u0628\u0648\u0631 \u0627\u0633\u062a \u0633\u0631\u067e\u0627 \u0628\u0627\u06cc\u0633\u062a\u062f<\/li>\n<li>\u06a9\u0627\u0631 \u06a9\u0631\u062f\u0646 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u067e\u0631\u0627\u0633\u062a\u0631\u0633<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%A9%D8%A7%D8%B1_%D8%B4%D8%BA%D9%84_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\"><\/span>\u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0634\u0627\u063a\u0644 \u067e\u0631\u062a\u0642\u0627\u0636\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0627\u0633\u062a. \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0634\u062a\u0647 \u062a\u062d\u0635\u06cc\u0644 \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f\u060c \u067e\u0633 \u0627\u0632 \u06af\u0630\u0631\u0627\u0646\u062f\u0646 \u062f\u0648\u0631\u0647 \u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u06cc \u0648\u0627\u0631\u062f \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0628\u062f\u0648\u0646 \u0634\u06a9 \u062f\u0627\u0634\u062a\u0646 \u06cc\u06a9 \u0631\u0632\u0648\u0645\u0647 \u0642\u0648\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0634\u0627\u0646\u0633 \u0627\u0641\u0631\u0627\u062f \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0634\u062f\u0646 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u062f.<\/p>\n<p>\u0686\u0646\u062f\u06cc\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a \u0634\u063a\u0644\u06cc \u0645\u062e\u062a\u0644\u0641 \u0628\u0631\u0627\u06cc \u0639\u0644\u0627\u0642\u0647\u200c\u0645\u0646\u062f\u0627\u0646 \u0628\u0647 \u0627\u06cc\u0646 \u0634\u063a\u0644 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0627\u06a9\u062b\u0631 \u062a\u06a9\u0646\u0633\u06cc\u0646\u200c\u0647\u0627\u06cc \u062c\u0631\u0627\u062d\u06cc \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0627\u0639\u0636\u0627\u06cc \u06a9\u0627\u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u062f\u0631 \u0628\u06cc\u0645\u0627\u0631\u0633\u062a\u0627\u0646\u200c\u0647\u0627 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0628\u0631\u062e\u06cc \u0627\u0632 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u0627\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631 \u0645\u0637\u0628\u200c\u0647\u0627\u06cc \u062e\u0635\u0648\u0635\u06cc \u0645\u0634\u063a\u0648\u0644 \u0628\u0647 \u06a9\u0627\u0631 \u0634\u0648\u0646\u062f. \u062f\u0631 \u0686\u0646\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637\u06cc\u060c \u0622\u0646\u200c\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0627\u0646\u062c\u0627\u0645 \u0639\u0645\u0644\u200c\u0647\u0627\u06cc \u062c\u0631\u0627\u062d\u06cc \u0633\u0631\u067e\u0627\u06cc\u06cc \u0628\u0647 \u067e\u0632\u0634\u06a9 \u062c\u0631\u0627\u062d \u06a9\u0645\u06a9 \u06a9\u0646\u0646\u062f. \u062f\u0631 \u0628\u0631\u062e\u06cc \u0645\u0648\u0627\u0631\u062f\u060c \u0627\u0645\u06a9\u0627\u0646 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u06cc\u0646 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u0627\u0646 \u062f\u0631 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u067e\u0632\u0634\u06a9\u06cc \u0646\u06cc\u0632 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%85%D8%AD%DB%8C%D8%B7_%DA%A9%D8%A7%D8%B1_%D8%AA%DA%A9%D9%86%D8%B3%DB%8C%D9%86%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\"><\/span>\u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631 \u062a\u06a9\u0646\u0633\u06cc\u0646\u200c\u0647\u0627\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062f\u0631 \u0628\u06cc\u0645\u0627\u0631\u0633\u062a\u0627\u0646\u060c \u0628\u0631\u0627\u06cc \u062d\u0641\u0638 \u0627\u06cc\u0645\u0646\u06cc \u062e\u0648\u062f \u0648 \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0628\u0627\u06cc\u062f \u0627\u0632 \u0645\u0627\u0633\u06a9\u060c \u062f\u0633\u062a\u06a9\u0634 \u0648 \u0627\u0633\u06a9\u0631\u0627\u0628 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0628\u0631\u0627\u06cc \u0645\u062f\u062a\u06cc \u0637\u0648\u0644\u0627\u0646\u06cc \u0633\u0631\u067e\u0627 \u0645\u06cc\u200c\u0627\u06cc\u0633\u062a\u06cc\u062f \u0648 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0634\u0627\u0647\u062f \u0635\u062d\u0646\u0647\u200c\u0647\u0627\u060c \u0628\u0648\u0647\u0627 \u0648 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0646\u0627\u062e\u0648\u0634\u0627\u06cc\u0646\u062f\u06cc \u0628\u0627\u0634\u06cc\u062f.<\/p>\n<p>\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u06a9\u0645\u06a9 \u0628\u0647 \u0622\u0645\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u0648 \u0627\u0646\u062c\u0627\u0645 \u062c\u0631\u0627\u062d\u06cc\u200c\u0647\u0627\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0646\u0645\u0648\u0646\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0641\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u0631\u0627\u06cc \u0622\u0646\u0627\u0644\u06cc\u0632 \u0622\u0632\u0645\u0627\u06cc\u0634\u06af\u0627\u0647\u06cc \u0631\u0627 \u0646\u06cc\u0632 \u0622\u0645\u0627\u062f\u0647 \u06a9\u0631\u062f\u0647\u060c \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u0645\u0631\u0627\u0642\u0628\u062a \u06a9\u0646\u06cc\u062f \u0648 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u062f\u0648\u0631 \u0628\u0631\u06cc\u0632\u06cc\u062f. \u062f\u0631 \u0645\u0648\u0631\u062f \u0628\u06cc\u0645\u0627\u0631\u0627\u0646\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u067e\u0627\u0646\u0633\u0645\u0627\u0646\u200c\u0647\u0627 \u0631\u0627 \u0639\u0648\u0636 \u06a9\u0631\u062f\u0647 \u0648 \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u0648\u0636\u0639\u06cc\u062a \u0622\u0646\u200c\u0647\u0627 \u062f\u0631 \u0627\u062a\u0627\u0642 \u0631\u06cc\u06a9\u0627\u0648\u0631\u06cc \u06a9\u0645\u06a9 \u06a9\u0646\u06cc\u062f. \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\u060c\u200c \u0634\u0645\u0627 \u0645\u0639\u0645\u0648\u0644\u0627 \u0627\u0648\u0644\u06cc\u0646 \u0641\u0631\u062f\u06cc \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u06a9\u0627\u0631 \u062f\u0631 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0631\u0627 \u0622\u063a\u0627\u0632 \u06a9\u0631\u062f\u0647 \u0648 \u0622\u062e\u0631\u06cc\u0646 \u0646\u0641\u0631\u06cc \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0627\u062a\u0627\u0642 \u062e\u0627\u0631\u062c \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p>\u06a9\u0627\u0631 \u06a9\u0631\u062f\u0646 \u062f\u0631 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0633\u062e\u062a \u0648 \u0637\u0627\u0642\u062a\u200c\u0641\u0631\u0633\u0627 \u0628\u0627\u0634\u062f. \u0628\u0627 \u0648\u062c\u0648\u062f \u0633\u0627\u0639\u062a\u200c\u0647\u0627 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0631\u06cc\u0632\u06cc \u062f\u0642\u06cc\u0642 \u0648 \u0622\u0645\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc\u060c \u0647\u0645\u06cc\u0634\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0627\u0648\u0631\u0698\u0627\u0646\u0633\u06cc \u0648 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u0631\u062e \u062f\u0647\u0646\u062f. \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0639\u0636\u0627\u06cc \u06a9\u0644\u06cc\u062f\u06cc \u062a\u06cc\u0645\u060c \u0628\u0627\u06cc\u062f \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631 \u0648 \u062c\u0631\u0627\u062d \u0631\u0627 \u062f\u0631 \u0637\u0648\u0644 \u0639\u0645\u0644 \u067e\u06cc\u0634\u200c\u0628\u06cc\u0646\u06cc \u06a9\u0631\u062f\u0647 \u0648 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062a\u0645\u0627\u0645 \u0645\u0631\u0627\u062d\u0644 \u0627\u06cc\u0646 \u0641\u0631\u0622\u06cc\u0646\u062f \u0628\u0647 \u062e\u0648\u0628\u06cc \u067e\u06cc\u0634 \u0645\u06cc\u200c\u0631\u0648\u0646\u062f.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u0645\u0634\u0627\u0647\u062f\u0647 \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0622\u06af\u0647\u06cc \u0647\u0627\u06cc <a href=\"https:\/\/karbord.io\/jobs\/surgery-coordinator\">\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<\/a> \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AD%D9%88%D8%B2%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%AA%D8%AE%D8%B5%D8%B5%DB%8C_%D8%B4%D8%BA%D9%84_%DA%A9%D8%A7%D8%B1%D8%B4%D9%86%D8%A7%D8%B3%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84\"><\/span>\u062d\u0648\u0632\u0647\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0627\u062a\u0627\u0642 \u0639\u0645\u0644<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u0633\u062a\u0627\u0646\u200c\u0647\u0627 \u0627\u0645\u06a9\u0627\u0646 \u06a9\u0627\u0631 \u06a9\u0631\u062f\u0646 \u062f\u0631 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u062c\u0631\u0627\u062d\u06cc \u0645\u062e\u062a\u0644\u0641 \u0631\u0627 \u062f\u0627\u0631\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644\u060c \u0628\u0631\u062e\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u062a\u06a9\u0646\u0633\u06cc\u0646\u200c\u0647\u0627 \u062a\u0646\u0647\u0627 \u062f\u0631 \u062d\u0648\u0632\u0647\u200c\u0647\u0627\u06cc\u06cc \u062e\u0627\u0635 \u0641\u0639\u0627\u0644\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0628\u0631\u062e\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u062d\u0648\u0632\u0647\u200c\u0647\u0627 \u0627\u0634\u0627\u0631\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a:<\/p>\n<ul>\n<li>\u062c\u0631\u0627\u062d\u06cc \u0642\u0644\u0628<\/li>\n<li>\u062c\u0631\u0627\u062d\u06cc \u0631\u0648\u062f\u0647<\/li>\n<li>\u0632\u0646\u0627\u0646 \u0648 \u0632\u0627\u06cc\u0645\u0627\u0646<\/li>\n<li>\u062c\u0631\u0627\u062d\u06cc \u0645\u063a\u0632 \u0648 \u0627\u0639\u0635\u0627\u0628<\/li>\n<li>\u062c\u0631\u0627\u062d\u06cc \u0686\u0634\u0645<\/li>\n<li>\u0641\u06a9 \u0648 \u0635\u0648\u0631\u062a<\/li>\n<li>\u06af\u0648\u0634 \u0648 \u062d\u0644\u0642 \u0648 \u0628\u06cc\u0646\u06cc<\/li>\n<li>\u062c\u0631\u0627\u062d\u06cc \u0627\u0631\u062a\u0648\u067e\u062f\u06cc<\/li>\n<li>\u062c\u0631\u0627\u062d\u06cc \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AD%D9%82%D9%88%D9%82_%D8%AA%DA%A9%D9%86%D8%B3%DB%8C%D9%86_%D8%A7%D8%AA%D8%A7%D9%82_%D8%B9%D9%85%D9%84_1402\"><\/span>\u062d\u0642\u0648\u0642 \u062a\u06a9\u0646\u0633\u06cc\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 1402<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3413\" src=\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician-3.jpg\" alt=\"\u062d\u0642\u0648\u0642 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\" width=\"900\" height=\"600\" srcset=\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician-3.jpg 900w, https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician-3-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/p>\n<p>\u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062f\u0631\u0622\u0645\u062f \u0631\u0634\u062a\u0647 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0628\u0647 \u0622\u0646 \u0639\u0644\u0627\u0642\u0647\u200c\u0645\u0646\u062f \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0639\u0648\u0627\u0645\u0644 \u0645\u062e\u062a\u0644\u0641\u06cc \u0631\u0648\u06cc \u0645\u0628\u0644\u063a \u0646\u0647\u0627\u06cc\u06cc \u062d\u0642\u0648\u0642 \u06cc\u06a9 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062a\u0627\u062b\u06cc\u0631 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u0646\u062f. \u0634\u0647\u0631 \u0645\u062d\u0644 \u0641\u0639\u0627\u0644\u06cc\u062a\u060c \u0628\u06cc\u0645\u0627\u0631\u0633\u062a\u0627\u0646\u06cc \u06a9\u0647 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u062f\u0631 \u0622\u0646 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0634\u062f\u0647\u060c \u0628\u062e\u0634\u06cc \u06a9\u0647 \u0627\u0648 \u062f\u0631 \u0622\u0646 \u0641\u0639\u0627\u0644\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0645\u06cc\u0632\u0627\u0646 \u062a\u062d\u0635\u06cc\u0644\u0627\u062a \u0648 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0627\u0648 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0627\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p>\u062f\u0631 \u0633\u0627\u0644 1402\u060c \u062f\u0631\u0622\u0645\u062f \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0628\u06cc\u0645\u0627\u0631\u0633\u062a\u0627\u0646\u200c\u0647\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u062a\u06a9\u0646\u0633\u06cc\u0646 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0628\u06cc\u0646 12 \u0627\u0644\u06cc 20 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062a\u0648\u0645\u0627\u0646 \u0627\u0633\u062a. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0622\u0646 \u062f\u0633\u062a\u0647 \u0627\u0632 \u062a\u06a9\u0646\u0633\u06cc\u0646\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u06a9\u0644\u06cc\u0646\u06cc\u06a9\u200c\u0647\u0627 \u0648 \u0645\u0637\u0628\u200c\u0647\u0627\u06cc \u062e\u0635\u0648\u0635\u06cc \u0641\u0639\u0627\u0644\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u062d\u0642\u0648\u0642 \u06a9\u0645\u062a\u0631\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u0646\u062f.<\/p>\n<p>\u0628\u06cc\u0634\u062a\u0631 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f: <a href=\"https:\/\/karbord.io\/blog\/operating-room-technician-salary\/\">\u0645\u06cc\u0632\u0627\u0646 \u062f\u0631\u0622\u0645\u062f \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u062f\u0631 \u0633\u0627\u0644 1403 \u0686\u0642\u062f\u0631 \u0627\u0633\u062a\u061f<\/a><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C\"><\/span>\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u0628\u0627 \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0622\u0634\u0646\u0627 \u0634\u062f\u06cc\u0645. \u0639\u0644\u0627\u0642\u0647\u200c\u0645\u0646\u062f\u0627\u0646 \u0628\u0647 \u0627\u06cc\u0646 \u0634\u063a\u0644 \u0628\u0627\u06cc\u062f \u0645\u062f\u0631\u06a9 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0631\u0634\u062a\u0647 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u0631\u0627 \u062f\u0631 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u0646\u062f \u0648 \u0628\u0627 \u067e\u0634\u062a \u0633\u0631\u06af\u0630\u0627\u0634\u062a\u0646 \u062f\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u0622\u0645\u0648\u0632\u06cc\u060c \u0622\u0645\u0627\u062f\u0647 \u0648\u0631\u0648\u062f \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0634\u0648\u0646\u062f. \u0627\u0644\u0628\u062a\u0647 \u0647\u0645\u0648\u0627\u0631\u0647 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u067e\u06cc\u0634 \u0627\u0632 \u0628\u0631\u06af\u0632\u06cc\u062f\u0646 \u0627\u06cc\u0646 \u0634\u063a\u0644\u060c \u0627\u0641\u0631\u0627\u062f \u0628\u0647 \u062e\u0648\u0628\u06cc \u0645\u0632\u0627\u06cc\u0627 \u0648 \u0645\u0639\u0627\u06cc\u0628 \u0622\u0646 \u0631\u0627 \u062f\u0631 \u0646\u0638\u06cc\u0631 \u0628\u06af\u06cc\u0631\u0646\u062f \u0648 \u0622\u06af\u0627\u0647\u0627\u0646\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u0646\u062f.<\/p>\n<p><strong>\u0645\u0646\u0628\u0639<\/strong>:<\/p>\n<p><a href=\"https:\/\/www.indeed.com\/career-advice\/career-development\/how-to-become-a-surgical-technician\" target=\"_blank\" rel=\"noopener\">indeed.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0639\u0636\u0627\u06cc \u06a9\u0644\u06cc\u062f\u06cc \u06a9\u0627\u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u062f\u0631 \u0647\u0631 \u0628\u06cc\u0645\u0627\u0631\u0633\u062a\u0627\u0646 \u0627\u0633\u062a. \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a \u0634\u063a\u0644\u06cc \u0641\u0639\u0627\u0644\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u062f\u0631 \u0645\u0648\u0641\u0642\u06cc\u062a\u200c\u0622\u0645\u06cc\u0632 \u0628\u0648\u062f\u0646 \u0639\u0645\u0644\u200c\u0647\u0627\u06cc \u062c\u0631\u0627\u062d\u06cc \u0645\u062e\u062a\u0644\u0641 \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u062f\u0627\u0631\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0628\u0627 \u0627\u06cc\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a \u0634\u063a\u0644\u06cc \u0622\u0634\u0646\u0627 \u0634\u062f\u0647 \u0648 \u0648\u0638\u0627\u06cc\u0641\u060c \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u060c \u0645\u0632\u0627\u06cc\u0627 \u0648 \u0645\u0639\u0627\u06cc\u0628\u060c \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u0645\u06cc\u0632\u0627\u0646 \u062d\u0642\u0648\u0642 \u0622\u0646 \u0631\u0627 \u0645\u0648\u0631\u062f [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":3414,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-3412","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-jobs-introduction","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 + \u0645\u06cc\u0632\u0627\u0646 \u062d\u0642\u0648\u0642- \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f<\/title>\r\n<meta name=\"description\" content=\"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0634\u0627\u063a\u0644 \u0645\u0647\u0645 \u0648 \u067e\u0631\u062a\u0642\u0627\u0636\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0627\u0633\u062a. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u0628\u0627 \u0627\u06cc\u0646 \u0634\u063a\u0644 \u0622\u0634\u0646\u0627 \u0645\u06cc \u0634\u0648\u06cc\u0645.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/\" \/>\r\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 + \u0645\u06cc\u0632\u0627\u0646 \u062d\u0642\u0648\u0642- \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\" \/>\r\n<meta property=\"og:description\" content=\"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0634\u0627\u063a\u0644 \u0645\u0647\u0645 \u0648 \u067e\u0631\u062a\u0642\u0627\u0636\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0627\u0633\u062a. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u0628\u0627 \u0627\u06cc\u0646 \u0634\u063a\u0644 \u0622\u0634\u0646\u0627 \u0645\u06cc \u0634\u0648\u06cc\u0645.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/\" \/>\r\n<meta property=\"og:site_name\" content=\"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-02-24T10:42:06+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-04-15T08:55:55+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"300\" \/>\r\n\t<meta property=\"og:image:height\" content=\"200\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"\u0646\u06cc\u0644\u0648\u0641\u0631 \u0645\u0698\u062f\u0647\u06cc\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0646\u06cc\u0644\u0648\u0641\u0631 \u0645\u0698\u062f\u0647\u06cc\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 \u062f\u0642\u06cc\u0642\u0647\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/\"},\"author\":{\"name\":\"\u0646\u06cc\u0644\u0648\u0641\u0631 \u0645\u0698\u062f\u0647\u06cc\",\"@id\":\"https:\/\/karbord.io\/blog\/#\/schema\/person\/718b2a40f4151b175f4daf2b322d3d11\"},\"headline\":\"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\u061b \u0634\u0631\u062d \u0648\u0638\u0627\u06cc\u0641\u060c \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u062d\u0642\u0648\u0642\",\"datePublished\":\"2024-02-24T10:42:06+00:00\",\"dateModified\":\"2024-04-15T08:55:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/\"},\"wordCount\":5944,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/karbord.io\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician.jpg\",\"articleSection\":[\"\u0645\u0639\u0631\u0641\u06cc \u0645\u0634\u0627\u063a\u0644\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/\",\"url\":\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/\",\"name\":\"\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 + \u0645\u06cc\u0632\u0627\u0646 \u062d\u0642\u0648\u0642- \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\",\"isPartOf\":{\"@id\":\"https:\/\/karbord.io\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician.jpg\",\"datePublished\":\"2024-02-24T10:42:06+00:00\",\"dateModified\":\"2024-04-15T08:55:55+00:00\",\"description\":\"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0634\u0627\u063a\u0644 \u0645\u0647\u0645 \u0648 \u067e\u0631\u062a\u0642\u0627\u0636\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0627\u0633\u062a. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u0628\u0627 \u0627\u06cc\u0646 \u0634\u063a\u0644 \u0622\u0634\u0646\u0627 \u0645\u06cc \u0634\u0648\u06cc\u0645.\",\"breadcrumb\":{\"@id\":\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#primaryimage\",\"url\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician.jpg\",\"contentUrl\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician.jpg\",\"width\":300,\"height\":200,\"caption\":\"\u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\/\/karbord.io\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\u061b \u0634\u0631\u062d \u0648\u0638\u0627\u06cc\u0641\u060c \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u062d\u0642\u0648\u0642\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/karbord.io\/blog\/#website\",\"url\":\"https:\/\/karbord.io\/blog\/\",\"name\":\"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\",\"description\":\"\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06a9\u0627\u0631\u06cc\u0627\u0628\u06cc \u0648 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u0633\u06cc\u0631 \u0634\u063a\u0644\u06cc\",\"publisher\":{\"@id\":\"https:\/\/karbord.io\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/karbord.io\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/karbord.io\/blog\/#organization\",\"name\":\"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\",\"url\":\"https:\/\/karbord.io\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/karbord.io\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/01\/favicon.ico\",\"contentUrl\":\"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/01\/favicon.ico\",\"width\":48,\"height\":48,\"caption\":\"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\"},\"image\":{\"@id\":\"https:\/\/karbord.io\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/karbord.io\/blog\/#\/schema\/person\/718b2a40f4151b175f4daf2b322d3d11\",\"name\":\"\u0646\u06cc\u0644\u0648\u0641\u0631 \u0645\u0698\u062f\u0647\u06cc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/karbord.io\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e5b5ef0c007ee8b89eae73382aa573?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e5b5ef0c007ee8b89eae73382aa573?s=96&d=mm&r=g\",\"caption\":\"\u0646\u06cc\u0644\u0648\u0641\u0631 \u0645\u0698\u062f\u0647\u06cc\"},\"url\":\"https:\/\/karbord.io\/blog\/author\/niloofar_mozh\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 + \u0645\u06cc\u0632\u0627\u0646 \u062d\u0642\u0648\u0642- \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","description":"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0634\u0627\u063a\u0644 \u0645\u0647\u0645 \u0648 \u067e\u0631\u062a\u0642\u0627\u0636\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0627\u0633\u062a. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u0628\u0627 \u0627\u06cc\u0646 \u0634\u063a\u0644 \u0622\u0634\u0646\u0627 \u0645\u06cc \u0634\u0648\u06cc\u0645.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 + \u0645\u06cc\u0632\u0627\u0646 \u062d\u0642\u0648\u0642- \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","og_description":"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0634\u0627\u063a\u0644 \u0645\u0647\u0645 \u0648 \u067e\u0631\u062a\u0642\u0627\u0636\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0627\u0633\u062a. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u0628\u0627 \u0627\u06cc\u0646 \u0634\u063a\u0644 \u0622\u0634\u0646\u0627 \u0645\u06cc \u0634\u0648\u06cc\u0645.","og_url":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/","og_site_name":"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","article_published_time":"2024-02-24T10:42:06+00:00","article_modified_time":"2024-04-15T08:55:55+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician.jpg","type":"image\/jpeg"}],"author":"\u0646\u06cc\u0644\u0648\u0641\u0631 \u0645\u0698\u062f\u0647\u06cc","twitter_card":"summary_large_image","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a":"\u0646\u06cc\u0644\u0648\u0641\u0631 \u0645\u0698\u062f\u0647\u06cc","\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646":"9 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#article","isPartOf":{"@id":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/"},"author":{"name":"\u0646\u06cc\u0644\u0648\u0641\u0631 \u0645\u0698\u062f\u0647\u06cc","@id":"https:\/\/karbord.io\/blog\/#\/schema\/person\/718b2a40f4151b175f4daf2b322d3d11"},"headline":"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\u061b \u0634\u0631\u062d \u0648\u0638\u0627\u06cc\u0641\u060c \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u062d\u0642\u0648\u0642","datePublished":"2024-02-24T10:42:06+00:00","dateModified":"2024-04-15T08:55:55+00:00","mainEntityOfPage":{"@id":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/"},"wordCount":5944,"commentCount":0,"publisher":{"@id":"https:\/\/karbord.io\/blog\/#organization"},"image":{"@id":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#primaryimage"},"thumbnailUrl":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician.jpg","articleSection":["\u0645\u0639\u0631\u0641\u06cc \u0645\u0634\u0627\u063a\u0644"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/","url":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/","name":"\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 + \u0645\u06cc\u0632\u0627\u0646 \u062d\u0642\u0648\u0642- \u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","isPartOf":{"@id":"https:\/\/karbord.io\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#primaryimage"},"image":{"@id":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#primaryimage"},"thumbnailUrl":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician.jpg","datePublished":"2024-02-24T10:42:06+00:00","dateModified":"2024-04-15T08:55:55+00:00","description":"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0634\u0627\u063a\u0644 \u0645\u0647\u0645 \u0648 \u067e\u0631\u062a\u0642\u0627\u0636\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0627\u0633\u062a. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u0628\u0627 \u0627\u06cc\u0646 \u0634\u063a\u0644 \u0622\u0634\u0646\u0627 \u0645\u06cc \u0634\u0648\u06cc\u0645.","breadcrumb":{"@id":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#primaryimage","url":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician.jpg","contentUrl":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2024\/02\/OR-technician.jpg","width":300,"height":200,"caption":"\u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644"},{"@type":"BreadcrumbList","@id":"https:\/\/karbord.io\/blog\/operating-room-technician-job-introduction\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/karbord.io\/blog\/"},{"@type":"ListItem","position":2,"name":"\u0634\u063a\u0644 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633 \u0627\u062a\u0627\u0642 \u0639\u0645\u0644\u061b \u0634\u0631\u062d \u0648\u0638\u0627\u06cc\u0641\u060c \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0648 \u062d\u0642\u0648\u0642"}]},{"@type":"WebSite","@id":"https:\/\/karbord.io\/blog\/#website","url":"https:\/\/karbord.io\/blog\/","name":"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","description":"\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u06a9\u0627\u0631\u06cc\u0627\u0628\u06cc \u0648 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u0633\u06cc\u0631 \u0634\u063a\u0644\u06cc","publisher":{"@id":"https:\/\/karbord.io\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/karbord.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/karbord.io\/blog\/#organization","name":"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f","url":"https:\/\/karbord.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/karbord.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/01\/favicon.ico","contentUrl":"https:\/\/karbord.io\/blog\/wp-content\/uploads\/2025\/01\/favicon.ico","width":48,"height":48,"caption":"\u0645\u062c\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f"},"image":{"@id":"https:\/\/karbord.io\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/karbord.io\/blog\/#\/schema\/person\/718b2a40f4151b175f4daf2b322d3d11","name":"\u0646\u06cc\u0644\u0648\u0641\u0631 \u0645\u0698\u062f\u0647\u06cc","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/karbord.io\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e5b5ef0c007ee8b89eae73382aa573?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e5b5ef0c007ee8b89eae73382aa573?s=96&d=mm&r=g","caption":"\u0646\u06cc\u0644\u0648\u0641\u0631 \u0645\u0698\u062f\u0647\u06cc"},"url":"https:\/\/karbord.io\/blog\/author\/niloofar_mozh\/"}]}},"_links":{"self":[{"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/posts\/3412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/comments?post=3412"}],"version-history":[{"count":5,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/posts\/3412\/revisions"}],"predecessor-version":[{"id":4243,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/posts\/3412\/revisions\/4243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/media\/3414"}],"wp:attachment":[{"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/media?parent=3412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/categories?post=3412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/karbord.io\/blog\/wp-json\/wp\/v2\/tags?post=3412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}